{"id":17932,"date":"2021-06-30T03:06:28","date_gmt":"2021-06-30T03:06:28","guid":{"rendered":"https:\/\/www.manabi.gob.ec\/?p=17932"},"modified":"2021-06-30T03:06:32","modified_gmt":"2021-06-30T03:06:32","slug":"autoridades-seccionales-resaltan-labor-del-gobierno-provincial-y-voluntad-de-trabajo-del-prefecto","status":"publish","type":"post","link":"https:\/\/www.manabi.gob.ec\/index.php\/autoridades-seccionales-resaltan-labor-del-gobierno-provincial-y-voluntad-de-trabajo-del-prefecto\/","title":{"rendered":"Autoridades seccionales resaltan labor del Gobierno Provincial y voluntad de trabajo del Prefecto"},"content":{"rendered":"\n<p>El trabajo que realiza el Gobierno de Manab\u00ed y el apoyo constante que reciben del prefecto Leonardo Orlando, fue destacado por autoridades seccionales de la provincia, durante la sesi\u00f3n solemne por los 65 a\u00f1os de creaci\u00f3n de la parroquia Quiroga, del cant\u00f3n Bol\u00edvar, cuyos representantes le entregaron una placa de reconocimiento.<\/p>\n\n\n\n<p>\u201cLa fortaleza de nuestra gesti\u00f3n en gran medida se debe al respaldo irrestricto de la Prefectura de Manab\u00ed, liderada acertadamente por usted, economista, Leonardo Orlando\u201d, dijo el presidente del GAD parroquial, Johan P\u00e1rraga.<\/p>\n\n\n\n<p>Criterios similares expresaron el Alcalde de Bol\u00edvar, Walter Cevallos, y el presidente del Consorcio de Gobiernos Parroquiales de Manab\u00ed, Yandri Bazurto.<\/p>\n\n\n\n<p>Desde el Gobierno Provincial tambi\u00e9n se ratific\u00f3 la voluntad de seguir trabajando junto a sus autoridades en proyectos y obras para el adelanto de esta parroquia .<\/p>\n\n\n\n<p>\u00abUstedes son nuestros mandantes, y el \u00fanico inter\u00e9s que tenemos como gobernantes, es el inter\u00e9s p\u00fablico, el inter\u00e9s de las grandes mayor\u00edas y de los m\u00e1s necesitados. Y ese es nuestro compromiso de honor y amor con Quiroga y con todo el noble pueblo de Bol\u00edvar\u00bb, manifest\u00f3 el Prefecto.<\/p>\n\n\n\n<p>Orlando convoc\u00f3, una vez m\u00e1s, a la unidad, como alternativa para salir adelante.<br>Adem\u00e1s, anunci\u00f3 nuevas intervenciones viales, tres puentes peatonales con una inversi\u00f3n superior a $200.000, y un Plan integral de reactivaci\u00f3n y seguridad para el transporte fluvial.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El trabajo que realiza el Gobierno de Manab\u00ed y el apoyo constante que reciben del prefecto Leonardo Orlando, fue destacado por autoridades seccionales de la provincia, durante la sesi\u00f3n solemne por los 65 a\u00f1os de creaci\u00f3n de la parroquia Quiroga, del cant\u00f3n Bol\u00edvar, cuyos representantes le entregaron una placa de reconocimiento. \u201cLa fortaleza de nuestra [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":17933,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[213,92,91],"tags":[],"class_list":["post-17932","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bolivar","category-noticias-manabi","category-todas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Autoridades seccionales resaltan labor del Gobierno Provincial y voluntad de trabajo del Prefecto - Prefectura de Manab\u00ed<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.manabi.gob.ec\/index.php\/autoridades-seccionales-resaltan-labor-del-gobierno-provincial-y-voluntad-de-trabajo-del-prefecto\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Autoridades seccionales resaltan labor del Gobierno Provincial y voluntad de trabajo del Prefecto - Prefectura de Manab\u00ed\" \/>\n<meta property=\"og:description\" content=\"El trabajo que realiza el Gobierno de Manab\u00ed y el apoyo constante que reciben del prefecto Leonardo Orlando, fue destacado por autoridades seccionales de la provincia, durante la sesi\u00f3n solemne por los 65 a\u00f1os de creaci\u00f3n de la parroquia Quiroga, del cant\u00f3n Bol\u00edvar, cuyos representantes le entregaron una placa de reconocimiento. \u201cLa fortaleza de nuestra [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.manabi.gob.ec\/index.php\/autoridades-seccionales-resaltan-labor-del-gobierno-provincial-y-voluntad-de-trabajo-del-prefecto\/\" \/>\n<meta property=\"og:site_name\" content=\"Prefectura de Manab\u00ed\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-30T03:06:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-30T03:06:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2021\/06\/SmartSelect_20210629-230540_WhatsApp.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1006\" \/>\n\t<meta property=\"og:image:height\" content=\"713\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/autoridades-seccionales-resaltan-labor-del-gobierno-provincial-y-voluntad-de-trabajo-del-prefecto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/autoridades-seccionales-resaltan-labor-del-gobierno-provincial-y-voluntad-de-trabajo-del-prefecto\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/#\\\/schema\\\/person\\\/cfc71bd68fe2703b779edcc292a49722\"},\"headline\":\"Autoridades seccionales resaltan labor del Gobierno Provincial y voluntad de trabajo del Prefecto\",\"datePublished\":\"2021-06-30T03:06:28+00:00\",\"dateModified\":\"2021-06-30T03:06:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/autoridades-seccionales-resaltan-labor-del-gobierno-provincial-y-voluntad-de-trabajo-del-prefecto\\\/\"},\"wordCount\":250,\"image\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/autoridades-seccionales-resaltan-labor-del-gobierno-provincial-y-voluntad-de-trabajo-del-prefecto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.manabi.gob.ec\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/SmartSelect_20210629-230540_WhatsApp.jpg\",\"articleSection\":[\"Bol\u00edvar\",\"Noticias\",\"Todas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/autoridades-seccionales-resaltan-labor-del-gobierno-provincial-y-voluntad-de-trabajo-del-prefecto\\\/\",\"url\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/autoridades-seccionales-resaltan-labor-del-gobierno-provincial-y-voluntad-de-trabajo-del-prefecto\\\/\",\"name\":\"Autoridades seccionales resaltan labor del Gobierno Provincial y voluntad de trabajo del Prefecto - Prefectura de Manab\u00ed\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/autoridades-seccionales-resaltan-labor-del-gobierno-provincial-y-voluntad-de-trabajo-del-prefecto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/autoridades-seccionales-resaltan-labor-del-gobierno-provincial-y-voluntad-de-trabajo-del-prefecto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.manabi.gob.ec\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/SmartSelect_20210629-230540_WhatsApp.jpg\",\"datePublished\":\"2021-06-30T03:06:28+00:00\",\"dateModified\":\"2021-06-30T03:06:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/#\\\/schema\\\/person\\\/cfc71bd68fe2703b779edcc292a49722\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/autoridades-seccionales-resaltan-labor-del-gobierno-provincial-y-voluntad-de-trabajo-del-prefecto\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/autoridades-seccionales-resaltan-labor-del-gobierno-provincial-y-voluntad-de-trabajo-del-prefecto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/autoridades-seccionales-resaltan-labor-del-gobierno-provincial-y-voluntad-de-trabajo-del-prefecto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.manabi.gob.ec\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/SmartSelect_20210629-230540_WhatsApp.jpg\",\"contentUrl\":\"https:\\\/\\\/www.manabi.gob.ec\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/SmartSelect_20210629-230540_WhatsApp.jpg\",\"width\":1006,\"height\":713},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/autoridades-seccionales-resaltan-labor-del-gobierno-provincial-y-voluntad-de-trabajo-del-prefecto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.manabi.gob.ec\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Autoridades seccionales resaltan labor del Gobierno Provincial y voluntad de trabajo del Prefecto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/#website\",\"url\":\"https:\\\/\\\/www.manabi.gob.ec\\\/\",\"name\":\"Prefectura de Manab\u00ed\",\"description\":\"P\u00e1gina web de la prefectura\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.manabi.gob.ec\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/#\\\/schema\\\/person\\\/cfc71bd68fe2703b779edcc292a49722\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23e9f919492b0a2f65aa168e0d8c5c867ea853b61deffbadf08c7031e15b8d78?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23e9f919492b0a2f65aa168e0d8c5c867ea853b61deffbadf08c7031e15b8d78?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/23e9f919492b0a2f65aa168e0d8c5c867ea853b61deffbadf08c7031e15b8d78?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\\\/\\\/www.manabi.gob.ec\"],\"url\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Autoridades seccionales resaltan labor del Gobierno Provincial y voluntad de trabajo del Prefecto - Prefectura de Manab\u00ed","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.manabi.gob.ec\/index.php\/autoridades-seccionales-resaltan-labor-del-gobierno-provincial-y-voluntad-de-trabajo-del-prefecto\/","og_locale":"es_ES","og_type":"article","og_title":"Autoridades seccionales resaltan labor del Gobierno Provincial y voluntad de trabajo del Prefecto - Prefectura de Manab\u00ed","og_description":"El trabajo que realiza el Gobierno de Manab\u00ed y el apoyo constante que reciben del prefecto Leonardo Orlando, fue destacado por autoridades seccionales de la provincia, durante la sesi\u00f3n solemne por los 65 a\u00f1os de creaci\u00f3n de la parroquia Quiroga, del cant\u00f3n Bol\u00edvar, cuyos representantes le entregaron una placa de reconocimiento. \u201cLa fortaleza de nuestra [&hellip;]","og_url":"https:\/\/www.manabi.gob.ec\/index.php\/autoridades-seccionales-resaltan-labor-del-gobierno-provincial-y-voluntad-de-trabajo-del-prefecto\/","og_site_name":"Prefectura de Manab\u00ed","article_published_time":"2021-06-30T03:06:28+00:00","article_modified_time":"2021-06-30T03:06:32+00:00","og_image":[{"width":1006,"height":713,"url":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2021\/06\/SmartSelect_20210629-230540_WhatsApp.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.manabi.gob.ec\/index.php\/autoridades-seccionales-resaltan-labor-del-gobierno-provincial-y-voluntad-de-trabajo-del-prefecto\/#article","isPartOf":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/autoridades-seccionales-resaltan-labor-del-gobierno-provincial-y-voluntad-de-trabajo-del-prefecto\/"},"author":{"name":"admin","@id":"https:\/\/www.manabi.gob.ec\/#\/schema\/person\/cfc71bd68fe2703b779edcc292a49722"},"headline":"Autoridades seccionales resaltan labor del Gobierno Provincial y voluntad de trabajo del Prefecto","datePublished":"2021-06-30T03:06:28+00:00","dateModified":"2021-06-30T03:06:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/autoridades-seccionales-resaltan-labor-del-gobierno-provincial-y-voluntad-de-trabajo-del-prefecto\/"},"wordCount":250,"image":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/autoridades-seccionales-resaltan-labor-del-gobierno-provincial-y-voluntad-de-trabajo-del-prefecto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2021\/06\/SmartSelect_20210629-230540_WhatsApp.jpg","articleSection":["Bol\u00edvar","Noticias","Todas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.manabi.gob.ec\/index.php\/autoridades-seccionales-resaltan-labor-del-gobierno-provincial-y-voluntad-de-trabajo-del-prefecto\/","url":"https:\/\/www.manabi.gob.ec\/index.php\/autoridades-seccionales-resaltan-labor-del-gobierno-provincial-y-voluntad-de-trabajo-del-prefecto\/","name":"Autoridades seccionales resaltan labor del Gobierno Provincial y voluntad de trabajo del Prefecto - Prefectura de Manab\u00ed","isPartOf":{"@id":"https:\/\/www.manabi.gob.ec\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/autoridades-seccionales-resaltan-labor-del-gobierno-provincial-y-voluntad-de-trabajo-del-prefecto\/#primaryimage"},"image":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/autoridades-seccionales-resaltan-labor-del-gobierno-provincial-y-voluntad-de-trabajo-del-prefecto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2021\/06\/SmartSelect_20210629-230540_WhatsApp.jpg","datePublished":"2021-06-30T03:06:28+00:00","dateModified":"2021-06-30T03:06:32+00:00","author":{"@id":"https:\/\/www.manabi.gob.ec\/#\/schema\/person\/cfc71bd68fe2703b779edcc292a49722"},"breadcrumb":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/autoridades-seccionales-resaltan-labor-del-gobierno-provincial-y-voluntad-de-trabajo-del-prefecto\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.manabi.gob.ec\/index.php\/autoridades-seccionales-resaltan-labor-del-gobierno-provincial-y-voluntad-de-trabajo-del-prefecto\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.manabi.gob.ec\/index.php\/autoridades-seccionales-resaltan-labor-del-gobierno-provincial-y-voluntad-de-trabajo-del-prefecto\/#primaryimage","url":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2021\/06\/SmartSelect_20210629-230540_WhatsApp.jpg","contentUrl":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2021\/06\/SmartSelect_20210629-230540_WhatsApp.jpg","width":1006,"height":713},{"@type":"BreadcrumbList","@id":"https:\/\/www.manabi.gob.ec\/index.php\/autoridades-seccionales-resaltan-labor-del-gobierno-provincial-y-voluntad-de-trabajo-del-prefecto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.manabi.gob.ec\/"},{"@type":"ListItem","position":2,"name":"Autoridades seccionales resaltan labor del Gobierno Provincial y voluntad de trabajo del Prefecto"}]},{"@type":"WebSite","@id":"https:\/\/www.manabi.gob.ec\/#website","url":"https:\/\/www.manabi.gob.ec\/","name":"Prefectura de Manab\u00ed","description":"P\u00e1gina web de la prefectura","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.manabi.gob.ec\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.manabi.gob.ec\/#\/schema\/person\/cfc71bd68fe2703b779edcc292a49722","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/23e9f919492b0a2f65aa168e0d8c5c867ea853b61deffbadf08c7031e15b8d78?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/23e9f919492b0a2f65aa168e0d8c5c867ea853b61deffbadf08c7031e15b8d78?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/23e9f919492b0a2f65aa168e0d8c5c867ea853b61deffbadf08c7031e15b8d78?s=96&d=mm&r=g","caption":"admin"},"sameAs":["http:\/\/www.manabi.gob.ec"],"url":"https:\/\/www.manabi.gob.ec\/index.php\/author\/admin\/"}]}},"jetpack_featured_media_url":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2021\/06\/SmartSelect_20210629-230540_WhatsApp.jpg","_links":{"self":[{"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/posts\/17932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/comments?post=17932"}],"version-history":[{"count":0,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/posts\/17932\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/media\/17933"}],"wp:attachment":[{"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/media?parent=17932"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/categories?post=17932"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/tags?post=17932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}