{"id":20741,"date":"2022-05-16T22:38:29","date_gmt":"2022-05-16T22:38:29","guid":{"rendered":"https:\/\/www.manabi.gob.ec\/?p=20741"},"modified":"2022-05-16T22:38:34","modified_gmt":"2022-05-16T22:38:34","slug":"mantenimiento-del-puente-metalico-de-picoaza-esta-en-la-recta-final","status":"publish","type":"post","link":"https:\/\/www.manabi.gob.ec\/index.php\/mantenimiento-del-puente-metalico-de-picoaza-esta-en-la-recta-final\/","title":{"rendered":"Mantenimiento del puente met\u00e1lico de Picoaz\u00e1 est\u00e1 en la recta final"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>Con la colocaci\u00f3n de las planchas de rodadura, avanza , la fase final de las labores de mantenimiento del puente met\u00e1lico 5 de junio, ubicado en el ingreso a la parroquia urbana Picoaz\u00e1, del cant\u00f3n Portoviejo. La obra registra un avance del 90%.<\/p>\n\n\n\n<p>\u201cHay que insistir que todas las planchas est\u00e1n totalmente culminadas. Lo que nos falta, y en eso estamos, es colocarlas y empernarlas. Son 102 planchas, de las cuales ya tenemos 33 colocadas\u201d, inform\u00f3 Carlos Villacreses, coordinador de infraestructura para el desarrollo del Gobierno Provincial de Manab\u00ed.<\/p>\n\n\n\n<p>Adem\u00e1s, se\u00f1al\u00f3 que esto terminar\u00e1 en pocos d\u00edas, tras lo cual se proceder\u00e1 a pintar el puente. Este viaducto de 49.50 metros de longitud fue construido por el Consejo Provincial el 24 de mayo de 1984, seg\u00fan consta en una placa informativa. Moradores destacan que desde entonces no se hab\u00eda realizado un mantenimiento integral a esta obra.<\/p>\n\n\n\n<p>\u201cEstamos alegres y orgullosos por lo que se est\u00e1 haciendo. Picoaz\u00e1 se lo agradece, se\u00f1or Prefecto\u201d, expres\u00f3 Yuri Moreira \u00c1lava, habitante de Picoaz\u00e1, mientras observaba las viejas y corro\u00eddas placas met\u00e1licas y daba \u201cgracias a Dios\u201d porque no se registr\u00f3 ninguna desgracia.<\/p>\n\n\n\n<p>Esta obra de mantenimiento se realiza en base a un convenio entre la Prefectura de Manab\u00ed y el GAD Municipal de Portoviejo, con una inversi\u00f3n de $154.088,83, m\u00e1s IVA. Incluye rehabilitaci\u00f3n de las planchas de rodadura, reparaci\u00f3n de las vigas transversales, iluminaci\u00f3n, y pintado de la estructura met\u00e1lica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con la colocaci\u00f3n de las planchas de rodadura, avanza , la fase final de las labores de mantenimiento del puente met\u00e1lico 5 de junio, ubicado en el ingreso a la parroquia urbana Picoaz\u00e1, del cant\u00f3n Portoviejo. La obra registra un avance del 90%. \u201cHay que insistir que todas las planchas est\u00e1n totalmente culminadas. Lo que [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":20742,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[142,92,181,132,91],"tags":[],"class_list":["post-20741","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-desarrollo-social","category-noticias-manabi","category-obra-publica","category-portoviejo","category-todas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mantenimiento del puente met\u00e1lico de Picoaz\u00e1 est\u00e1 en la recta final - Prefectura de Manab\u00ed<\/title>\n<meta name=\"description\" content=\"Con la colocaci\u00f3n de las planchas de rodadura, avanza , la fase final de las labores de mantenimiento del puente met\u00e1lico 5 de junio, ubicado en el ingreso a la parroquia urbana Picoaz\u00e1, del cant\u00f3n Portoviejo. La obra registra un avance del 90%.\u201cHay que insistir que todas las planchas est\u00e1n totalmente culminadas. Lo que nos falta, y en eso estamos, es colocarlas y empernarlas. Son 102 planchas, de las cuales ya tenemos 33 colocadas\u201d, inform\u00f3 Carlos Villacreses, coordinador de infraestructura para el desarrollo del Gobierno Provincial de Manab\u00ed.Adem\u00e1s, se\u00f1al\u00f3 que esto terminar\u00e1 en pocos d\u00edas, tras lo cual se proceder\u00e1 a pintar el puente. Este viaducto de 49.50 metros de longitud fue construido por el Consejo Provincial el 24 de mayo de 1984, seg\u00fan consta en una placa informativa. Moradores destacan que desde entonces no se hab\u00eda realizado un mantenimiento integral a esta obra.\u201cEstamos alegres y orgullosos por lo que se est\u00e1 haciendo. Picoaz\u00e1 se lo agradece, se\u00f1or Prefecto\u201d, expres\u00f3 Yuri Moreira \u00c1lava, habitante de Picoaz\u00e1, mientras observaba las viejas y corro\u00eddas placas met\u00e1licas y daba \u201cgracias a Dios\u201d porque no se registr\u00f3 ninguna desgracia.Esta obra de mantenimiento se realiza en base a un convenio entre la Prefectura de Manab\u00ed y el GAD Municipal de Portoviejo, con una inversi\u00f3n de $154.088,83, m\u00e1s IVA. Incluye rehabilitaci\u00f3n de las planchas de rodadura, reparaci\u00f3n de las vigas transversales, iluminaci\u00f3n, y pintado de la estructura met\u00e1lica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.manabi.gob.ec\/index.php\/mantenimiento-del-puente-metalico-de-picoaza-esta-en-la-recta-final\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mantenimiento del puente met\u00e1lico de Picoaz\u00e1 est\u00e1 en la recta final - Prefectura de Manab\u00ed\" \/>\n<meta property=\"og:description\" content=\"Con la colocaci\u00f3n de las planchas de rodadura, avanza , la fase final de las labores de mantenimiento del puente met\u00e1lico 5 de junio, ubicado en el ingreso a la parroquia urbana Picoaz\u00e1, del cant\u00f3n Portoviejo. La obra registra un avance del 90%.\u201cHay que insistir que todas las planchas est\u00e1n totalmente culminadas. Lo que nos falta, y en eso estamos, es colocarlas y empernarlas. Son 102 planchas, de las cuales ya tenemos 33 colocadas\u201d, inform\u00f3 Carlos Villacreses, coordinador de infraestructura para el desarrollo del Gobierno Provincial de Manab\u00ed.Adem\u00e1s, se\u00f1al\u00f3 que esto terminar\u00e1 en pocos d\u00edas, tras lo cual se proceder\u00e1 a pintar el puente. Este viaducto de 49.50 metros de longitud fue construido por el Consejo Provincial el 24 de mayo de 1984, seg\u00fan consta en una placa informativa. Moradores destacan que desde entonces no se hab\u00eda realizado un mantenimiento integral a esta obra.\u201cEstamos alegres y orgullosos por lo que se est\u00e1 haciendo. Picoaz\u00e1 se lo agradece, se\u00f1or Prefecto\u201d, expres\u00f3 Yuri Moreira \u00c1lava, habitante de Picoaz\u00e1, mientras observaba las viejas y corro\u00eddas placas met\u00e1licas y daba \u201cgracias a Dios\u201d porque no se registr\u00f3 ninguna desgracia.Esta obra de mantenimiento se realiza en base a un convenio entre la Prefectura de Manab\u00ed y el GAD Municipal de Portoviejo, con una inversi\u00f3n de $154.088,83, m\u00e1s IVA. Incluye rehabilitaci\u00f3n de las planchas de rodadura, reparaci\u00f3n de las vigas transversales, iluminaci\u00f3n, y pintado de la estructura met\u00e1lica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.manabi.gob.ec\/index.php\/mantenimiento-del-puente-metalico-de-picoaza-esta-en-la-recta-final\/\" \/>\n<meta property=\"og:site_name\" content=\"Prefectura de Manab\u00ed\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-16T22:38:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-16T22:38:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-16-at-3.32.33-PM.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lui Ochoa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lui Ochoa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/mantenimiento-del-puente-metalico-de-picoaza-esta-en-la-recta-final\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/mantenimiento-del-puente-metalico-de-picoaza-esta-en-la-recta-final\\\/\"},\"author\":{\"name\":\"Lui Ochoa\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/#\\\/schema\\\/person\\\/c4f117989332ad723a6ced5994aa7d7a\"},\"headline\":\"Mantenimiento del puente met\u00e1lico de Picoaz\u00e1 est\u00e1 en la recta final\",\"datePublished\":\"2022-05-16T22:38:29+00:00\",\"dateModified\":\"2022-05-16T22:38:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/mantenimiento-del-puente-metalico-de-picoaza-esta-en-la-recta-final\\\/\"},\"wordCount\":257,\"image\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/mantenimiento-del-puente-metalico-de-picoaza-esta-en-la-recta-final\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.manabi.gob.ec\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/WhatsApp-Image-2022-05-16-at-3.32.33-PM.jpeg\",\"articleSection\":[\"Desarrollo Social\",\"Noticias\",\"Obra P\u00fablica\",\"Portoviejo\",\"Todas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/mantenimiento-del-puente-metalico-de-picoaza-esta-en-la-recta-final\\\/\",\"url\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/mantenimiento-del-puente-metalico-de-picoaza-esta-en-la-recta-final\\\/\",\"name\":\"Mantenimiento del puente met\u00e1lico de Picoaz\u00e1 est\u00e1 en la recta final - Prefectura de Manab\u00ed\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/mantenimiento-del-puente-metalico-de-picoaza-esta-en-la-recta-final\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/mantenimiento-del-puente-metalico-de-picoaza-esta-en-la-recta-final\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.manabi.gob.ec\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/WhatsApp-Image-2022-05-16-at-3.32.33-PM.jpeg\",\"datePublished\":\"2022-05-16T22:38:29+00:00\",\"dateModified\":\"2022-05-16T22:38:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/#\\\/schema\\\/person\\\/c4f117989332ad723a6ced5994aa7d7a\"},\"description\":\"Con la colocaci\u00f3n de las planchas de rodadura, avanza , la fase final de las labores de mantenimiento del puente met\u00e1lico 5 de junio, ubicado en el ingreso a la parroquia urbana Picoaz\u00e1, del cant\u00f3n Portoviejo. La obra registra un avance del 90%.\u201cHay que insistir que todas las planchas est\u00e1n totalmente culminadas. Lo que nos falta, y en eso estamos, es colocarlas y empernarlas. Son 102 planchas, de las cuales ya tenemos 33 colocadas\u201d, inform\u00f3 Carlos Villacreses, coordinador de infraestructura para el desarrollo del Gobierno Provincial de Manab\u00ed.Adem\u00e1s, se\u00f1al\u00f3 que esto terminar\u00e1 en pocos d\u00edas, tras lo cual se proceder\u00e1 a pintar el puente. Este viaducto de 49.50 metros de longitud fue construido por el Consejo Provincial el 24 de mayo de 1984, seg\u00fan consta en una placa informativa. Moradores destacan que desde entonces no se hab\u00eda realizado un mantenimiento integral a esta obra.\u201cEstamos alegres y orgullosos por lo que se est\u00e1 haciendo. Picoaz\u00e1 se lo agradece, se\u00f1or Prefecto\u201d, expres\u00f3 Yuri Moreira \u00c1lava, habitante de Picoaz\u00e1, mientras observaba las viejas y corro\u00eddas placas met\u00e1licas y daba \u201cgracias a Dios\u201d porque no se registr\u00f3 ninguna desgracia.Esta obra de mantenimiento se realiza en base a un convenio entre la Prefectura de Manab\u00ed y el GAD Municipal de Portoviejo, con una inversi\u00f3n de $154.088,83, m\u00e1s IVA. Incluye rehabilitaci\u00f3n de las planchas de rodadura, reparaci\u00f3n de las vigas transversales, iluminaci\u00f3n, y pintado de la estructura met\u00e1lica.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/mantenimiento-del-puente-metalico-de-picoaza-esta-en-la-recta-final\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/mantenimiento-del-puente-metalico-de-picoaza-esta-en-la-recta-final\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/mantenimiento-del-puente-metalico-de-picoaza-esta-en-la-recta-final\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.manabi.gob.ec\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/WhatsApp-Image-2022-05-16-at-3.32.33-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.manabi.gob.ec\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/WhatsApp-Image-2022-05-16-at-3.32.33-PM.jpeg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/mantenimiento-del-puente-metalico-de-picoaza-esta-en-la-recta-final\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.manabi.gob.ec\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mantenimiento del puente met\u00e1lico de Picoaz\u00e1 est\u00e1 en la recta final\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/#website\",\"url\":\"https:\\\/\\\/www.manabi.gob.ec\\\/\",\"name\":\"Prefectura de Manab\u00ed\",\"description\":\"P\u00e1gina web de la prefectura\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.manabi.gob.ec\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/#\\\/schema\\\/person\\\/c4f117989332ad723a6ced5994aa7d7a\",\"name\":\"Lui Ochoa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g\",\"caption\":\"Lui Ochoa\"},\"url\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/author\\\/lochoa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mantenimiento del puente met\u00e1lico de Picoaz\u00e1 est\u00e1 en la recta final - Prefectura de Manab\u00ed","description":"Con la colocaci\u00f3n de las planchas de rodadura, avanza , la fase final de las labores de mantenimiento del puente met\u00e1lico 5 de junio, ubicado en el ingreso a la parroquia urbana Picoaz\u00e1, del cant\u00f3n Portoviejo. La obra registra un avance del 90%.\u201cHay que insistir que todas las planchas est\u00e1n totalmente culminadas. Lo que nos falta, y en eso estamos, es colocarlas y empernarlas. Son 102 planchas, de las cuales ya tenemos 33 colocadas\u201d, inform\u00f3 Carlos Villacreses, coordinador de infraestructura para el desarrollo del Gobierno Provincial de Manab\u00ed.Adem\u00e1s, se\u00f1al\u00f3 que esto terminar\u00e1 en pocos d\u00edas, tras lo cual se proceder\u00e1 a pintar el puente. Este viaducto de 49.50 metros de longitud fue construido por el Consejo Provincial el 24 de mayo de 1984, seg\u00fan consta en una placa informativa. Moradores destacan que desde entonces no se hab\u00eda realizado un mantenimiento integral a esta obra.\u201cEstamos alegres y orgullosos por lo que se est\u00e1 haciendo. Picoaz\u00e1 se lo agradece, se\u00f1or Prefecto\u201d, expres\u00f3 Yuri Moreira \u00c1lava, habitante de Picoaz\u00e1, mientras observaba las viejas y corro\u00eddas placas met\u00e1licas y daba \u201cgracias a Dios\u201d porque no se registr\u00f3 ninguna desgracia.Esta obra de mantenimiento se realiza en base a un convenio entre la Prefectura de Manab\u00ed y el GAD Municipal de Portoviejo, con una inversi\u00f3n de $154.088,83, m\u00e1s IVA. Incluye rehabilitaci\u00f3n de las planchas de rodadura, reparaci\u00f3n de las vigas transversales, iluminaci\u00f3n, y pintado de la estructura met\u00e1lica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.manabi.gob.ec\/index.php\/mantenimiento-del-puente-metalico-de-picoaza-esta-en-la-recta-final\/","og_locale":"es_ES","og_type":"article","og_title":"Mantenimiento del puente met\u00e1lico de Picoaz\u00e1 est\u00e1 en la recta final - Prefectura de Manab\u00ed","og_description":"Con la colocaci\u00f3n de las planchas de rodadura, avanza , la fase final de las labores de mantenimiento del puente met\u00e1lico 5 de junio, ubicado en el ingreso a la parroquia urbana Picoaz\u00e1, del cant\u00f3n Portoviejo. La obra registra un avance del 90%.\u201cHay que insistir que todas las planchas est\u00e1n totalmente culminadas. Lo que nos falta, y en eso estamos, es colocarlas y empernarlas. Son 102 planchas, de las cuales ya tenemos 33 colocadas\u201d, inform\u00f3 Carlos Villacreses, coordinador de infraestructura para el desarrollo del Gobierno Provincial de Manab\u00ed.Adem\u00e1s, se\u00f1al\u00f3 que esto terminar\u00e1 en pocos d\u00edas, tras lo cual se proceder\u00e1 a pintar el puente. Este viaducto de 49.50 metros de longitud fue construido por el Consejo Provincial el 24 de mayo de 1984, seg\u00fan consta en una placa informativa. Moradores destacan que desde entonces no se hab\u00eda realizado un mantenimiento integral a esta obra.\u201cEstamos alegres y orgullosos por lo que se est\u00e1 haciendo. Picoaz\u00e1 se lo agradece, se\u00f1or Prefecto\u201d, expres\u00f3 Yuri Moreira \u00c1lava, habitante de Picoaz\u00e1, mientras observaba las viejas y corro\u00eddas placas met\u00e1licas y daba \u201cgracias a Dios\u201d porque no se registr\u00f3 ninguna desgracia.Esta obra de mantenimiento se realiza en base a un convenio entre la Prefectura de Manab\u00ed y el GAD Municipal de Portoviejo, con una inversi\u00f3n de $154.088,83, m\u00e1s IVA. Incluye rehabilitaci\u00f3n de las planchas de rodadura, reparaci\u00f3n de las vigas transversales, iluminaci\u00f3n, y pintado de la estructura met\u00e1lica.","og_url":"https:\/\/www.manabi.gob.ec\/index.php\/mantenimiento-del-puente-metalico-de-picoaza-esta-en-la-recta-final\/","og_site_name":"Prefectura de Manab\u00ed","article_published_time":"2022-05-16T22:38:29+00:00","article_modified_time":"2022-05-16T22:38:34+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-16-at-3.32.33-PM.jpeg","type":"image\/jpeg"}],"author":"Lui Ochoa","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Lui Ochoa","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.manabi.gob.ec\/index.php\/mantenimiento-del-puente-metalico-de-picoaza-esta-en-la-recta-final\/#article","isPartOf":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/mantenimiento-del-puente-metalico-de-picoaza-esta-en-la-recta-final\/"},"author":{"name":"Lui Ochoa","@id":"https:\/\/www.manabi.gob.ec\/#\/schema\/person\/c4f117989332ad723a6ced5994aa7d7a"},"headline":"Mantenimiento del puente met\u00e1lico de Picoaz\u00e1 est\u00e1 en la recta final","datePublished":"2022-05-16T22:38:29+00:00","dateModified":"2022-05-16T22:38:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/mantenimiento-del-puente-metalico-de-picoaza-esta-en-la-recta-final\/"},"wordCount":257,"image":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/mantenimiento-del-puente-metalico-de-picoaza-esta-en-la-recta-final\/#primaryimage"},"thumbnailUrl":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-16-at-3.32.33-PM.jpeg","articleSection":["Desarrollo Social","Noticias","Obra P\u00fablica","Portoviejo","Todas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.manabi.gob.ec\/index.php\/mantenimiento-del-puente-metalico-de-picoaza-esta-en-la-recta-final\/","url":"https:\/\/www.manabi.gob.ec\/index.php\/mantenimiento-del-puente-metalico-de-picoaza-esta-en-la-recta-final\/","name":"Mantenimiento del puente met\u00e1lico de Picoaz\u00e1 est\u00e1 en la recta final - Prefectura de Manab\u00ed","isPartOf":{"@id":"https:\/\/www.manabi.gob.ec\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/mantenimiento-del-puente-metalico-de-picoaza-esta-en-la-recta-final\/#primaryimage"},"image":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/mantenimiento-del-puente-metalico-de-picoaza-esta-en-la-recta-final\/#primaryimage"},"thumbnailUrl":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-16-at-3.32.33-PM.jpeg","datePublished":"2022-05-16T22:38:29+00:00","dateModified":"2022-05-16T22:38:34+00:00","author":{"@id":"https:\/\/www.manabi.gob.ec\/#\/schema\/person\/c4f117989332ad723a6ced5994aa7d7a"},"description":"Con la colocaci\u00f3n de las planchas de rodadura, avanza , la fase final de las labores de mantenimiento del puente met\u00e1lico 5 de junio, ubicado en el ingreso a la parroquia urbana Picoaz\u00e1, del cant\u00f3n Portoviejo. La obra registra un avance del 90%.\u201cHay que insistir que todas las planchas est\u00e1n totalmente culminadas. Lo que nos falta, y en eso estamos, es colocarlas y empernarlas. Son 102 planchas, de las cuales ya tenemos 33 colocadas\u201d, inform\u00f3 Carlos Villacreses, coordinador de infraestructura para el desarrollo del Gobierno Provincial de Manab\u00ed.Adem\u00e1s, se\u00f1al\u00f3 que esto terminar\u00e1 en pocos d\u00edas, tras lo cual se proceder\u00e1 a pintar el puente. Este viaducto de 49.50 metros de longitud fue construido por el Consejo Provincial el 24 de mayo de 1984, seg\u00fan consta en una placa informativa. Moradores destacan que desde entonces no se hab\u00eda realizado un mantenimiento integral a esta obra.\u201cEstamos alegres y orgullosos por lo que se est\u00e1 haciendo. Picoaz\u00e1 se lo agradece, se\u00f1or Prefecto\u201d, expres\u00f3 Yuri Moreira \u00c1lava, habitante de Picoaz\u00e1, mientras observaba las viejas y corro\u00eddas placas met\u00e1licas y daba \u201cgracias a Dios\u201d porque no se registr\u00f3 ninguna desgracia.Esta obra de mantenimiento se realiza en base a un convenio entre la Prefectura de Manab\u00ed y el GAD Municipal de Portoviejo, con una inversi\u00f3n de $154.088,83, m\u00e1s IVA. Incluye rehabilitaci\u00f3n de las planchas de rodadura, reparaci\u00f3n de las vigas transversales, iluminaci\u00f3n, y pintado de la estructura met\u00e1lica.","breadcrumb":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/mantenimiento-del-puente-metalico-de-picoaza-esta-en-la-recta-final\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.manabi.gob.ec\/index.php\/mantenimiento-del-puente-metalico-de-picoaza-esta-en-la-recta-final\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.manabi.gob.ec\/index.php\/mantenimiento-del-puente-metalico-de-picoaza-esta-en-la-recta-final\/#primaryimage","url":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-16-at-3.32.33-PM.jpeg","contentUrl":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-16-at-3.32.33-PM.jpeg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.manabi.gob.ec\/index.php\/mantenimiento-del-puente-metalico-de-picoaza-esta-en-la-recta-final\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.manabi.gob.ec\/"},{"@type":"ListItem","position":2,"name":"Mantenimiento del puente met\u00e1lico de Picoaz\u00e1 est\u00e1 en la recta final"}]},{"@type":"WebSite","@id":"https:\/\/www.manabi.gob.ec\/#website","url":"https:\/\/www.manabi.gob.ec\/","name":"Prefectura de Manab\u00ed","description":"P\u00e1gina web de la prefectura","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.manabi.gob.ec\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.manabi.gob.ec\/#\/schema\/person\/c4f117989332ad723a6ced5994aa7d7a","name":"Lui Ochoa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g","caption":"Lui Ochoa"},"url":"https:\/\/www.manabi.gob.ec\/index.php\/author\/lochoa\/"}]}},"jetpack_featured_media_url":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-16-at-3.32.33-PM.jpeg","_links":{"self":[{"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/posts\/20741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/comments?post=20741"}],"version-history":[{"count":0,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/posts\/20741\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/media\/20742"}],"wp:attachment":[{"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/media?parent=20741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/categories?post=20741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/tags?post=20741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}