{"id":24676,"date":"2023-05-31T20:14:26","date_gmt":"2023-05-31T20:14:26","guid":{"rendered":"https:\/\/www.manabi.gob.ec\/?p=24676"},"modified":"2023-05-31T20:14:32","modified_gmt":"2023-05-31T20:14:32","slug":"manabi-y-mexico-fortalecen-lazos-de-hermandad","status":"publish","type":"post","link":"https:\/\/www.manabi.gob.ec\/index.php\/manabi-y-mexico-fortalecen-lazos-de-hermandad\/","title":{"rendered":"Manab\u00ed y M\u00e9xico, fortalecen lazos de hermandad"},"content":{"rendered":"\n<p>La Embajadora de M\u00e9xico en Ecuador Raquel Serur, realiz\u00f3 una visita protocolaria al prefecto Leonardo Orlando, este martes 30 de mayo.<\/p>\n\n\n\n<p>Con M\u00e9xico nos unen lazos de hermandad muy fuertes, dijo el prefecto Leonardo Orlando, \u00abEstamos totalmente abiertos para trabajar coordinadamente en proyectos que beneficien a los manabitas\u00bb, manifest\u00f3 el Prefecto.<\/p>\n\n\n\n<p>La autoridad provincial inform\u00f3 que la Prefectura de Manab\u00ed, se encuentra trabajando con la Universidad Aut\u00f3noma de San Luis de Potos\u00ed de la Rep\u00fablica Federal de M\u00e9xico para la construcci\u00f3n de la matriz insumo producto provincial.<\/p>\n\n\n\n<p>La Embajadora Serur explic\u00f3 al Prefecto el Programa Escuelas M\u00e9xico, iniciativa que se origin\u00f3 en el a\u00f1o 1996, con el compromiso de promover el desarrollo de la ni\u00f1ez. El programa est\u00e1 dirigido a la formaci\u00f3n educativa de Latinoam\u00e9rica y el Caribe es coordinado por la Agencia Mexicana de Cooperaci\u00f3n Internacional para el Desarrollo (AMEXCID).<\/p>\n\n\n\n<p>\u00abEn Ecuador tenemos nueve escuelas, y en Manab\u00ed funcionan tres\u00bb, sostuvo Serur.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Embajadora de M\u00e9xico en Ecuador Raquel Serur, realiz\u00f3 una visita protocolaria al prefecto Leonardo Orlando, este martes 30 de mayo. Con M\u00e9xico nos unen lazos de hermandad muy fuertes, dijo el prefecto Leonardo Orlando, \u00abEstamos totalmente abiertos para trabajar coordinadamente en proyectos que beneficien a los manabitas\u00bb, manifest\u00f3 el Prefecto. La autoridad provincial inform\u00f3 [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":24677,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[142,92,91],"tags":[],"class_list":["post-24676","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-desarrollo-social","category-noticias-manabi","category-todas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Manab\u00ed y M\u00e9xico, fortalecen lazos de hermandad - Prefectura de Manab\u00ed<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.manabi.gob.ec\/index.php\/manabi-y-mexico-fortalecen-lazos-de-hermandad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Manab\u00ed y M\u00e9xico, fortalecen lazos de hermandad - Prefectura de Manab\u00ed\" \/>\n<meta property=\"og:description\" content=\"La Embajadora de M\u00e9xico en Ecuador Raquel Serur, realiz\u00f3 una visita protocolaria al prefecto Leonardo Orlando, este martes 30 de mayo. Con M\u00e9xico nos unen lazos de hermandad muy fuertes, dijo el prefecto Leonardo Orlando, \u00abEstamos totalmente abiertos para trabajar coordinadamente en proyectos que beneficien a los manabitas\u00bb, manifest\u00f3 el Prefecto. La autoridad provincial inform\u00f3 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.manabi.gob.ec\/index.php\/manabi-y-mexico-fortalecen-lazos-de-hermandad\/\" \/>\n<meta property=\"og:site_name\" content=\"Prefectura de Manab\u00ed\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-31T20:14:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-31T20:14:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-30-at-17.40.09.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1296\" \/>\n\t<meta property=\"og:image:height\" content=\"864\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lui Ochoa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lui Ochoa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/manabi-y-mexico-fortalecen-lazos-de-hermandad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/manabi-y-mexico-fortalecen-lazos-de-hermandad\\\/\"},\"author\":{\"name\":\"Lui Ochoa\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/#\\\/schema\\\/person\\\/c4f117989332ad723a6ced5994aa7d7a\"},\"headline\":\"Manab\u00ed y M\u00e9xico, fortalecen lazos de hermandad\",\"datePublished\":\"2023-05-31T20:14:26+00:00\",\"dateModified\":\"2023-05-31T20:14:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/manabi-y-mexico-fortalecen-lazos-de-hermandad\\\/\"},\"wordCount\":171,\"image\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/manabi-y-mexico-fortalecen-lazos-de-hermandad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.manabi.gob.ec\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/WhatsApp-Image-2023-05-30-at-17.40.09.jpeg\",\"articleSection\":[\"Desarrollo Social\",\"Noticias\",\"Todas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/manabi-y-mexico-fortalecen-lazos-de-hermandad\\\/\",\"url\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/manabi-y-mexico-fortalecen-lazos-de-hermandad\\\/\",\"name\":\"Manab\u00ed y M\u00e9xico, fortalecen lazos de hermandad - Prefectura de Manab\u00ed\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/manabi-y-mexico-fortalecen-lazos-de-hermandad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/manabi-y-mexico-fortalecen-lazos-de-hermandad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.manabi.gob.ec\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/WhatsApp-Image-2023-05-30-at-17.40.09.jpeg\",\"datePublished\":\"2023-05-31T20:14:26+00:00\",\"dateModified\":\"2023-05-31T20:14:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/#\\\/schema\\\/person\\\/c4f117989332ad723a6ced5994aa7d7a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/manabi-y-mexico-fortalecen-lazos-de-hermandad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/manabi-y-mexico-fortalecen-lazos-de-hermandad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/manabi-y-mexico-fortalecen-lazos-de-hermandad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.manabi.gob.ec\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/WhatsApp-Image-2023-05-30-at-17.40.09.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.manabi.gob.ec\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/WhatsApp-Image-2023-05-30-at-17.40.09.jpeg\",\"width\":1296,\"height\":864},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/manabi-y-mexico-fortalecen-lazos-de-hermandad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.manabi.gob.ec\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Manab\u00ed y M\u00e9xico, fortalecen lazos de hermandad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/#website\",\"url\":\"https:\\\/\\\/www.manabi.gob.ec\\\/\",\"name\":\"Prefectura de Manab\u00ed\",\"description\":\"P\u00e1gina web de la prefectura\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.manabi.gob.ec\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/#\\\/schema\\\/person\\\/c4f117989332ad723a6ced5994aa7d7a\",\"name\":\"Lui Ochoa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g\",\"caption\":\"Lui Ochoa\"},\"url\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/author\\\/lochoa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Manab\u00ed y M\u00e9xico, fortalecen lazos de hermandad - Prefectura de Manab\u00ed","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.manabi.gob.ec\/index.php\/manabi-y-mexico-fortalecen-lazos-de-hermandad\/","og_locale":"es_ES","og_type":"article","og_title":"Manab\u00ed y M\u00e9xico, fortalecen lazos de hermandad - Prefectura de Manab\u00ed","og_description":"La Embajadora de M\u00e9xico en Ecuador Raquel Serur, realiz\u00f3 una visita protocolaria al prefecto Leonardo Orlando, este martes 30 de mayo. Con M\u00e9xico nos unen lazos de hermandad muy fuertes, dijo el prefecto Leonardo Orlando, \u00abEstamos totalmente abiertos para trabajar coordinadamente en proyectos que beneficien a los manabitas\u00bb, manifest\u00f3 el Prefecto. La autoridad provincial inform\u00f3 [&hellip;]","og_url":"https:\/\/www.manabi.gob.ec\/index.php\/manabi-y-mexico-fortalecen-lazos-de-hermandad\/","og_site_name":"Prefectura de Manab\u00ed","article_published_time":"2023-05-31T20:14:26+00:00","article_modified_time":"2023-05-31T20:14:32+00:00","og_image":[{"width":1296,"height":864,"url":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-30-at-17.40.09.jpeg","type":"image\/jpeg"}],"author":"Lui Ochoa","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Lui Ochoa","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.manabi.gob.ec\/index.php\/manabi-y-mexico-fortalecen-lazos-de-hermandad\/#article","isPartOf":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/manabi-y-mexico-fortalecen-lazos-de-hermandad\/"},"author":{"name":"Lui Ochoa","@id":"https:\/\/www.manabi.gob.ec\/#\/schema\/person\/c4f117989332ad723a6ced5994aa7d7a"},"headline":"Manab\u00ed y M\u00e9xico, fortalecen lazos de hermandad","datePublished":"2023-05-31T20:14:26+00:00","dateModified":"2023-05-31T20:14:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/manabi-y-mexico-fortalecen-lazos-de-hermandad\/"},"wordCount":171,"image":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/manabi-y-mexico-fortalecen-lazos-de-hermandad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-30-at-17.40.09.jpeg","articleSection":["Desarrollo Social","Noticias","Todas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.manabi.gob.ec\/index.php\/manabi-y-mexico-fortalecen-lazos-de-hermandad\/","url":"https:\/\/www.manabi.gob.ec\/index.php\/manabi-y-mexico-fortalecen-lazos-de-hermandad\/","name":"Manab\u00ed y M\u00e9xico, fortalecen lazos de hermandad - Prefectura de Manab\u00ed","isPartOf":{"@id":"https:\/\/www.manabi.gob.ec\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/manabi-y-mexico-fortalecen-lazos-de-hermandad\/#primaryimage"},"image":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/manabi-y-mexico-fortalecen-lazos-de-hermandad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-30-at-17.40.09.jpeg","datePublished":"2023-05-31T20:14:26+00:00","dateModified":"2023-05-31T20:14:32+00:00","author":{"@id":"https:\/\/www.manabi.gob.ec\/#\/schema\/person\/c4f117989332ad723a6ced5994aa7d7a"},"breadcrumb":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/manabi-y-mexico-fortalecen-lazos-de-hermandad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.manabi.gob.ec\/index.php\/manabi-y-mexico-fortalecen-lazos-de-hermandad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.manabi.gob.ec\/index.php\/manabi-y-mexico-fortalecen-lazos-de-hermandad\/#primaryimage","url":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-30-at-17.40.09.jpeg","contentUrl":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-30-at-17.40.09.jpeg","width":1296,"height":864},{"@type":"BreadcrumbList","@id":"https:\/\/www.manabi.gob.ec\/index.php\/manabi-y-mexico-fortalecen-lazos-de-hermandad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.manabi.gob.ec\/"},{"@type":"ListItem","position":2,"name":"Manab\u00ed y M\u00e9xico, fortalecen lazos de hermandad"}]},{"@type":"WebSite","@id":"https:\/\/www.manabi.gob.ec\/#website","url":"https:\/\/www.manabi.gob.ec\/","name":"Prefectura de Manab\u00ed","description":"P\u00e1gina web de la prefectura","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.manabi.gob.ec\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.manabi.gob.ec\/#\/schema\/person\/c4f117989332ad723a6ced5994aa7d7a","name":"Lui Ochoa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g","caption":"Lui Ochoa"},"url":"https:\/\/www.manabi.gob.ec\/index.php\/author\/lochoa\/"}]}},"jetpack_featured_media_url":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-30-at-17.40.09.jpeg","_links":{"self":[{"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/posts\/24676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/comments?post=24676"}],"version-history":[{"count":0,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/posts\/24676\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/media\/24677"}],"wp:attachment":[{"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/media?parent=24676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/categories?post=24676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/tags?post=24676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}