{"id":25008,"date":"2023-07-03T22:42:46","date_gmt":"2023-07-03T22:42:46","guid":{"rendered":"https:\/\/www.manabi.gob.ec\/?p=25008"},"modified":"2023-07-03T22:42:52","modified_gmt":"2023-07-03T22:42:52","slug":"prefecto-supervisa-obras-viales-y-de-riego-y-drenaje-en-tosagua","status":"publish","type":"post","link":"https:\/\/www.manabi.gob.ec\/index.php\/prefecto-supervisa-obras-viales-y-de-riego-y-drenaje-en-tosagua\/","title":{"rendered":"Prefecto supervisa obras viales y de riego y drenaje en Tosagua"},"content":{"rendered":"\n<p>Este martes 27 de junio, el Prefecto de Manab\u00ed, Leonardo Orlando, junto con el Alcalde de Tosagua, Romel Cede\u00f1o, y un equipo t\u00e9cnico de la Prefectura, se traslad\u00f3 a la v\u00eda El Tambo &#8211; Juncal &#8211; Larrea, en el cant\u00f3n Tosagua, para llevar a cabo una supervisi\u00f3n de los trabajos de reconformaci\u00f3n de la calzada a nivel de sub- base que se est\u00e1 realizando en esta importante ruta.<\/p>\n\n\n\n<p><br>Esta obra de 9 kil\u00f3metros se ejecuta a trav\u00e9s de un convenio firmado entre la Prefectura de Manab\u00ed y el GAD cantonal y beneficia a m\u00e1s de 17 comunidades que hay en el sector.<\/p>\n\n\n\n<p><br>Posteriormente, el equipo liderado por el Prefecto Orlando se traslad\u00f3 a otros sectores donde la Prefectura lleva a cabo la limpieza y desazolve del canal Macontra &#8211; Matapalo, desde el puente San Ram\u00f3n hasta el sector de Larrea, se tiene previsto intervenir tres kil\u00f3metros con la limpieza y desazolve, y hasta ahora se ha avanzado en un kil\u00f3metro.<br>Estos trabajos son de vital importancia porque permiten prevenir inundaciones y asegurar un adecuado drenaje del agua durante \u00e9pocas de lluvia.<\/p>\n\n\n\n<p><br>Tambi\u00e9n se supervis\u00f3 los trabajos de reconformaci\u00f3n de la v\u00eda Bachillero &#8211; Monte Oscuro.<br>\u201cEstamos felices de estar hoy en la capital maicera del Ecuador, todo nuestro respaldo a los agricultores para que puedan sacar su producci\u00f3n, por eso las v\u00edas y los sistemas de riego, limpieza de canales en los que estamos trabajando, y que hoy recorrimos, con estas intervenciones se busca mitigar los posibles efectos del inminente Fen\u00f3meno del Ni\u00f1o\u201d, dijo el prefecto Orlando.<br>La primera autoridad provincial ratific\u00f3 su compromiso para seguir trabajando por la provincia de la mano con los GAD\u2019s cantonales y parroquiales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este martes 27 de junio, el Prefecto de Manab\u00ed, Leonardo Orlando, junto con el Alcalde de Tosagua, Romel Cede\u00f1o, y un equipo t\u00e9cnico de la Prefectura, se traslad\u00f3 a la v\u00eda El Tambo &#8211; Juncal &#8211; Larrea, en el cant\u00f3n Tosagua, para llevar a cabo una supervisi\u00f3n de los trabajos de reconformaci\u00f3n de la calzada [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":25009,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[142,92,181,339,340,89,91,130],"tags":[],"class_list":["post-25008","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-desarrollo-social","category-noticias-manabi","category-obra-publica","category-plan-invernal","category-plan-invernal-plan-invernal","category-riego-drenaje","category-todas","category-tosagua"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prefecto supervisa obras viales y de riego y drenaje en Tosagua - Prefectura de Manab\u00ed<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.manabi.gob.ec\/index.php\/prefecto-supervisa-obras-viales-y-de-riego-y-drenaje-en-tosagua\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prefecto supervisa obras viales y de riego y drenaje en Tosagua - Prefectura de Manab\u00ed\" \/>\n<meta property=\"og:description\" content=\"Este martes 27 de junio, el Prefecto de Manab\u00ed, Leonardo Orlando, junto con el Alcalde de Tosagua, Romel Cede\u00f1o, y un equipo t\u00e9cnico de la Prefectura, se traslad\u00f3 a la v\u00eda El Tambo &#8211; Juncal &#8211; Larrea, en el cant\u00f3n Tosagua, para llevar a cabo una supervisi\u00f3n de los trabajos de reconformaci\u00f3n de la calzada [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.manabi.gob.ec\/index.php\/prefecto-supervisa-obras-viales-y-de-riego-y-drenaje-en-tosagua\/\" \/>\n<meta property=\"og:site_name\" content=\"Prefectura de Manab\u00ed\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-03T22:42:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-03T22:42:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-06-28-at-10.36.26.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"684\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lui Ochoa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lui Ochoa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/prefecto-supervisa-obras-viales-y-de-riego-y-drenaje-en-tosagua\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/prefecto-supervisa-obras-viales-y-de-riego-y-drenaje-en-tosagua\\\/\"},\"author\":{\"name\":\"Lui Ochoa\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/#\\\/schema\\\/person\\\/c4f117989332ad723a6ced5994aa7d7a\"},\"headline\":\"Prefecto supervisa obras viales y de riego y drenaje en Tosagua\",\"datePublished\":\"2023-07-03T22:42:46+00:00\",\"dateModified\":\"2023-07-03T22:42:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/prefecto-supervisa-obras-viales-y-de-riego-y-drenaje-en-tosagua\\\/\"},\"wordCount\":307,\"image\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/prefecto-supervisa-obras-viales-y-de-riego-y-drenaje-en-tosagua\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.manabi.gob.ec\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/WhatsApp-Image-2023-06-28-at-10.36.26.jpeg\",\"articleSection\":[\"Desarrollo Social\",\"Noticias\",\"Obra P\u00fablica\",\"Plan Invernal\",\"PLAN INVERNAL\",\"Riego y drenaje\",\"Todas\",\"Tosagua\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/prefecto-supervisa-obras-viales-y-de-riego-y-drenaje-en-tosagua\\\/\",\"url\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/prefecto-supervisa-obras-viales-y-de-riego-y-drenaje-en-tosagua\\\/\",\"name\":\"Prefecto supervisa obras viales y de riego y drenaje en Tosagua - Prefectura de Manab\u00ed\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/prefecto-supervisa-obras-viales-y-de-riego-y-drenaje-en-tosagua\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/prefecto-supervisa-obras-viales-y-de-riego-y-drenaje-en-tosagua\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.manabi.gob.ec\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/WhatsApp-Image-2023-06-28-at-10.36.26.jpeg\",\"datePublished\":\"2023-07-03T22:42:46+00:00\",\"dateModified\":\"2023-07-03T22:42:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/#\\\/schema\\\/person\\\/c4f117989332ad723a6ced5994aa7d7a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/prefecto-supervisa-obras-viales-y-de-riego-y-drenaje-en-tosagua\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/prefecto-supervisa-obras-viales-y-de-riego-y-drenaje-en-tosagua\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/prefecto-supervisa-obras-viales-y-de-riego-y-drenaje-en-tosagua\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.manabi.gob.ec\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/WhatsApp-Image-2023-06-28-at-10.36.26.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.manabi.gob.ec\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/WhatsApp-Image-2023-06-28-at-10.36.26.jpeg\",\"width\":1024,\"height\":684},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/prefecto-supervisa-obras-viales-y-de-riego-y-drenaje-en-tosagua\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.manabi.gob.ec\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prefecto supervisa obras viales y de riego y drenaje en Tosagua\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/#website\",\"url\":\"https:\\\/\\\/www.manabi.gob.ec\\\/\",\"name\":\"Prefectura de Manab\u00ed\",\"description\":\"P\u00e1gina web de la prefectura\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.manabi.gob.ec\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/#\\\/schema\\\/person\\\/c4f117989332ad723a6ced5994aa7d7a\",\"name\":\"Lui Ochoa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g\",\"caption\":\"Lui Ochoa\"},\"url\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/author\\\/lochoa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prefecto supervisa obras viales y de riego y drenaje en Tosagua - Prefectura de Manab\u00ed","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.manabi.gob.ec\/index.php\/prefecto-supervisa-obras-viales-y-de-riego-y-drenaje-en-tosagua\/","og_locale":"es_ES","og_type":"article","og_title":"Prefecto supervisa obras viales y de riego y drenaje en Tosagua - Prefectura de Manab\u00ed","og_description":"Este martes 27 de junio, el Prefecto de Manab\u00ed, Leonardo Orlando, junto con el Alcalde de Tosagua, Romel Cede\u00f1o, y un equipo t\u00e9cnico de la Prefectura, se traslad\u00f3 a la v\u00eda El Tambo &#8211; Juncal &#8211; Larrea, en el cant\u00f3n Tosagua, para llevar a cabo una supervisi\u00f3n de los trabajos de reconformaci\u00f3n de la calzada [&hellip;]","og_url":"https:\/\/www.manabi.gob.ec\/index.php\/prefecto-supervisa-obras-viales-y-de-riego-y-drenaje-en-tosagua\/","og_site_name":"Prefectura de Manab\u00ed","article_published_time":"2023-07-03T22:42:46+00:00","article_modified_time":"2023-07-03T22:42:52+00:00","og_image":[{"width":1024,"height":684,"url":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-06-28-at-10.36.26.jpeg","type":"image\/jpeg"}],"author":"Lui Ochoa","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Lui Ochoa","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.manabi.gob.ec\/index.php\/prefecto-supervisa-obras-viales-y-de-riego-y-drenaje-en-tosagua\/#article","isPartOf":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/prefecto-supervisa-obras-viales-y-de-riego-y-drenaje-en-tosagua\/"},"author":{"name":"Lui Ochoa","@id":"https:\/\/www.manabi.gob.ec\/#\/schema\/person\/c4f117989332ad723a6ced5994aa7d7a"},"headline":"Prefecto supervisa obras viales y de riego y drenaje en Tosagua","datePublished":"2023-07-03T22:42:46+00:00","dateModified":"2023-07-03T22:42:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/prefecto-supervisa-obras-viales-y-de-riego-y-drenaje-en-tosagua\/"},"wordCount":307,"image":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/prefecto-supervisa-obras-viales-y-de-riego-y-drenaje-en-tosagua\/#primaryimage"},"thumbnailUrl":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-06-28-at-10.36.26.jpeg","articleSection":["Desarrollo Social","Noticias","Obra P\u00fablica","Plan Invernal","PLAN INVERNAL","Riego y drenaje","Todas","Tosagua"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.manabi.gob.ec\/index.php\/prefecto-supervisa-obras-viales-y-de-riego-y-drenaje-en-tosagua\/","url":"https:\/\/www.manabi.gob.ec\/index.php\/prefecto-supervisa-obras-viales-y-de-riego-y-drenaje-en-tosagua\/","name":"Prefecto supervisa obras viales y de riego y drenaje en Tosagua - Prefectura de Manab\u00ed","isPartOf":{"@id":"https:\/\/www.manabi.gob.ec\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/prefecto-supervisa-obras-viales-y-de-riego-y-drenaje-en-tosagua\/#primaryimage"},"image":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/prefecto-supervisa-obras-viales-y-de-riego-y-drenaje-en-tosagua\/#primaryimage"},"thumbnailUrl":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-06-28-at-10.36.26.jpeg","datePublished":"2023-07-03T22:42:46+00:00","dateModified":"2023-07-03T22:42:52+00:00","author":{"@id":"https:\/\/www.manabi.gob.ec\/#\/schema\/person\/c4f117989332ad723a6ced5994aa7d7a"},"breadcrumb":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/prefecto-supervisa-obras-viales-y-de-riego-y-drenaje-en-tosagua\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.manabi.gob.ec\/index.php\/prefecto-supervisa-obras-viales-y-de-riego-y-drenaje-en-tosagua\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.manabi.gob.ec\/index.php\/prefecto-supervisa-obras-viales-y-de-riego-y-drenaje-en-tosagua\/#primaryimage","url":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-06-28-at-10.36.26.jpeg","contentUrl":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-06-28-at-10.36.26.jpeg","width":1024,"height":684},{"@type":"BreadcrumbList","@id":"https:\/\/www.manabi.gob.ec\/index.php\/prefecto-supervisa-obras-viales-y-de-riego-y-drenaje-en-tosagua\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.manabi.gob.ec\/"},{"@type":"ListItem","position":2,"name":"Prefecto supervisa obras viales y de riego y drenaje en Tosagua"}]},{"@type":"WebSite","@id":"https:\/\/www.manabi.gob.ec\/#website","url":"https:\/\/www.manabi.gob.ec\/","name":"Prefectura de Manab\u00ed","description":"P\u00e1gina web de la prefectura","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.manabi.gob.ec\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.manabi.gob.ec\/#\/schema\/person\/c4f117989332ad723a6ced5994aa7d7a","name":"Lui Ochoa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g","caption":"Lui Ochoa"},"url":"https:\/\/www.manabi.gob.ec\/index.php\/author\/lochoa\/"}]}},"jetpack_featured_media_url":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-06-28-at-10.36.26.jpeg","_links":{"self":[{"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/posts\/25008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/comments?post=25008"}],"version-history":[{"count":0,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/posts\/25008\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/media\/25009"}],"wp:attachment":[{"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/media?parent=25008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/categories?post=25008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/tags?post=25008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}