{"id":25047,"date":"2023-07-04T00:17:59","date_gmt":"2023-07-04T00:17:59","guid":{"rendered":"https:\/\/www.manabi.gob.ec\/?p=25047"},"modified":"2023-07-04T00:18:05","modified_gmt":"2023-07-04T00:18:05","slug":"prefectura-socializa-proyecto-de-politica-publica","status":"publish","type":"post","link":"https:\/\/www.manabi.gob.ec\/index.php\/prefectura-socializa-proyecto-de-politica-publica\/","title":{"rendered":"PREFECTURA SOCIALIZA PROYECTO DE POL\u00cdTICA P\u00daBLICA"},"content":{"rendered":"\n<p>La Prefectura desarroll\u00f3 un taller con las instituciones p\u00fablicas de la provincia, en el que se socializ\u00f3 el proyecto de la primera Pol\u00edtica P\u00fablica Provincial para garantizar los derechos de las personas LGBTIQ+.<\/p>\n\n\n\n<p>El evento se desarroll\u00f3 la ma\u00f1ana de este 3 de julio, en el sal\u00f3n de actos de la Prefectura de Manab\u00ed, en el que particip\u00f3 el Subsecretario de Diversidades del Ministerio de la Mujer y Derechos Humanos, Alexander Guano, quien felicit\u00f3 a la Prefectura por este trabajo articulado que se viene haciendo por lograr respeto y derecho para todos los grupos de la sociedad.<\/p>\n\n\n\n<p>\u201cMi reconocimiento al Gobierno de Manab\u00ed por pasar del discurso a la acci\u00f3n, al implementar pol\u00edticas p\u00fablicas en el respeto de derechos para todos y todas\u201d, dijo Guano, quien present\u00f3 informaci\u00f3n de la Pol\u00edtica p\u00fablica de derechos en el pa\u00eds y el trabajo que se hace desde el Gobierno Central en garant\u00eda de derechos.<\/p>\n\n\n\n<p>El objetivo de este taller es generar espacios de di\u00e1logo y de an\u00e1lisis sobre la importancia de proteger y promover los derechos de esta comunidad, as\u00ed como establecer lineamientos y acciones concretas para su inclusi\u00f3n efectiva, manifest\u00f3 Yael Seni, Directora de Desarrollo Humano de la Prefectura, quien dio la bienvenida a los asistentes a nombre del Prefecto, Leonardo Orlando. \u201cTenemos una pol\u00edtica p\u00fablica que promueve la cultura de paz\u201d, dijo.<\/p>\n\n\n\n<p>Daniela de La Fuente, m\u00e9dico de Prefectura, detall\u00f3 sobre la gesti\u00f3n social y de g\u00e9nero que se desarrolla la Prefectura en la provincia, a trav\u00e9s de los programas que mantiene la Direcci\u00f3n de Desarrollo Humano que protege el derecho y la igualdad en la provincia.<\/p>\n\n\n\n<p>Las acciones propuestas en la Primera Pol\u00edtica P\u00fablica LGBTIQ+ para la provincia, fueron presentada por el soci\u00f3logo Brayan Mendoza, t\u00e9cnico de la Direcci\u00f3n de Desarrollo Social, y present\u00f3 cifras de investigaciones desarrolladas en la provincia, que determinan que el 70,9 de personas ha vivido discriminaci\u00f3n en su entorno familiar, un 61,4% ha sufrido violencia f\u00edsica, y un 172% ha sido expulsada de su casa.<\/p>\n\n\n\n<p>El proceso de elaboraci\u00f3n de este proyecto se inici\u00f3 en agosto del 2022, con el objetivo de generar un espacio de di\u00e1logo y reflexi\u00f3n sobre la importancia de proteger y promover los derechos, as\u00ed como establecer lineamientos y acciones concretas para su inclusi\u00f3n efectiva.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Prefectura desarroll\u00f3 un taller con las instituciones p\u00fablicas de la provincia, en el que se socializ\u00f3 el proyecto de la primera Pol\u00edtica P\u00fablica Provincial para garantizar los derechos de las personas LGBTIQ+. El evento se desarroll\u00f3 la ma\u00f1ana de este 3 de julio, en el sal\u00f3n de actos de la Prefectura de Manab\u00ed, en [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":25048,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[142,92,72,91],"tags":[],"class_list":["post-25047","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-desarrollo-social","category-noticias-manabi","category-salud","category-todas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PREFECTURA SOCIALIZA PROYECTO DE POL\u00cdTICA P\u00daBLICA - Prefectura de Manab\u00ed<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.manabi.gob.ec\/index.php\/prefectura-socializa-proyecto-de-politica-publica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PREFECTURA SOCIALIZA PROYECTO DE POL\u00cdTICA P\u00daBLICA - Prefectura de Manab\u00ed\" \/>\n<meta property=\"og:description\" content=\"La Prefectura desarroll\u00f3 un taller con las instituciones p\u00fablicas de la provincia, en el que se socializ\u00f3 el proyecto de la primera Pol\u00edtica P\u00fablica Provincial para garantizar los derechos de las personas LGBTIQ+. El evento se desarroll\u00f3 la ma\u00f1ana de este 3 de julio, en el sal\u00f3n de actos de la Prefectura de Manab\u00ed, en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.manabi.gob.ec\/index.php\/prefectura-socializa-proyecto-de-politica-publica\/\" \/>\n<meta property=\"og:site_name\" content=\"Prefectura de Manab\u00ed\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-04T00:17:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-04T00:18:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-03-at-14.16.44.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"827\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lui Ochoa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lui Ochoa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/prefectura-socializa-proyecto-de-politica-publica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/prefectura-socializa-proyecto-de-politica-publica\\\/\"},\"author\":{\"name\":\"Lui Ochoa\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/#\\\/schema\\\/person\\\/c4f117989332ad723a6ced5994aa7d7a\"},\"headline\":\"PREFECTURA SOCIALIZA PROYECTO DE POL\u00cdTICA P\u00daBLICA\",\"datePublished\":\"2023-07-04T00:17:59+00:00\",\"dateModified\":\"2023-07-04T00:18:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/prefectura-socializa-proyecto-de-politica-publica\\\/\"},\"wordCount\":411,\"image\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/prefectura-socializa-proyecto-de-politica-publica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.manabi.gob.ec\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/WhatsApp-Image-2023-07-03-at-14.16.44.jpeg\",\"articleSection\":[\"Desarrollo Social\",\"Noticias\",\"salud\",\"Todas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/prefectura-socializa-proyecto-de-politica-publica\\\/\",\"url\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/prefectura-socializa-proyecto-de-politica-publica\\\/\",\"name\":\"PREFECTURA SOCIALIZA PROYECTO DE POL\u00cdTICA P\u00daBLICA - Prefectura de Manab\u00ed\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/prefectura-socializa-proyecto-de-politica-publica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/prefectura-socializa-proyecto-de-politica-publica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.manabi.gob.ec\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/WhatsApp-Image-2023-07-03-at-14.16.44.jpeg\",\"datePublished\":\"2023-07-04T00:17:59+00:00\",\"dateModified\":\"2023-07-04T00:18:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/#\\\/schema\\\/person\\\/c4f117989332ad723a6ced5994aa7d7a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/prefectura-socializa-proyecto-de-politica-publica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/prefectura-socializa-proyecto-de-politica-publica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/prefectura-socializa-proyecto-de-politica-publica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.manabi.gob.ec\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/WhatsApp-Image-2023-07-03-at-14.16.44.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.manabi.gob.ec\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/WhatsApp-Image-2023-07-03-at-14.16.44.jpeg\",\"width\":1024,\"height\":827},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/prefectura-socializa-proyecto-de-politica-publica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.manabi.gob.ec\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PREFECTURA SOCIALIZA PROYECTO DE POL\u00cdTICA P\u00daBLICA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/#website\",\"url\":\"https:\\\/\\\/www.manabi.gob.ec\\\/\",\"name\":\"Prefectura de Manab\u00ed\",\"description\":\"P\u00e1gina web de la prefectura\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.manabi.gob.ec\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/#\\\/schema\\\/person\\\/c4f117989332ad723a6ced5994aa7d7a\",\"name\":\"Lui Ochoa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g\",\"caption\":\"Lui Ochoa\"},\"url\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/author\\\/lochoa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PREFECTURA SOCIALIZA PROYECTO DE POL\u00cdTICA P\u00daBLICA - Prefectura de Manab\u00ed","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.manabi.gob.ec\/index.php\/prefectura-socializa-proyecto-de-politica-publica\/","og_locale":"es_ES","og_type":"article","og_title":"PREFECTURA SOCIALIZA PROYECTO DE POL\u00cdTICA P\u00daBLICA - Prefectura de Manab\u00ed","og_description":"La Prefectura desarroll\u00f3 un taller con las instituciones p\u00fablicas de la provincia, en el que se socializ\u00f3 el proyecto de la primera Pol\u00edtica P\u00fablica Provincial para garantizar los derechos de las personas LGBTIQ+. El evento se desarroll\u00f3 la ma\u00f1ana de este 3 de julio, en el sal\u00f3n de actos de la Prefectura de Manab\u00ed, en [&hellip;]","og_url":"https:\/\/www.manabi.gob.ec\/index.php\/prefectura-socializa-proyecto-de-politica-publica\/","og_site_name":"Prefectura de Manab\u00ed","article_published_time":"2023-07-04T00:17:59+00:00","article_modified_time":"2023-07-04T00:18:05+00:00","og_image":[{"width":1024,"height":827,"url":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-03-at-14.16.44.jpeg","type":"image\/jpeg"}],"author":"Lui Ochoa","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Lui Ochoa","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.manabi.gob.ec\/index.php\/prefectura-socializa-proyecto-de-politica-publica\/#article","isPartOf":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/prefectura-socializa-proyecto-de-politica-publica\/"},"author":{"name":"Lui Ochoa","@id":"https:\/\/www.manabi.gob.ec\/#\/schema\/person\/c4f117989332ad723a6ced5994aa7d7a"},"headline":"PREFECTURA SOCIALIZA PROYECTO DE POL\u00cdTICA P\u00daBLICA","datePublished":"2023-07-04T00:17:59+00:00","dateModified":"2023-07-04T00:18:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/prefectura-socializa-proyecto-de-politica-publica\/"},"wordCount":411,"image":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/prefectura-socializa-proyecto-de-politica-publica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-03-at-14.16.44.jpeg","articleSection":["Desarrollo Social","Noticias","salud","Todas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.manabi.gob.ec\/index.php\/prefectura-socializa-proyecto-de-politica-publica\/","url":"https:\/\/www.manabi.gob.ec\/index.php\/prefectura-socializa-proyecto-de-politica-publica\/","name":"PREFECTURA SOCIALIZA PROYECTO DE POL\u00cdTICA P\u00daBLICA - Prefectura de Manab\u00ed","isPartOf":{"@id":"https:\/\/www.manabi.gob.ec\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/prefectura-socializa-proyecto-de-politica-publica\/#primaryimage"},"image":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/prefectura-socializa-proyecto-de-politica-publica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-03-at-14.16.44.jpeg","datePublished":"2023-07-04T00:17:59+00:00","dateModified":"2023-07-04T00:18:05+00:00","author":{"@id":"https:\/\/www.manabi.gob.ec\/#\/schema\/person\/c4f117989332ad723a6ced5994aa7d7a"},"breadcrumb":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/prefectura-socializa-proyecto-de-politica-publica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.manabi.gob.ec\/index.php\/prefectura-socializa-proyecto-de-politica-publica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.manabi.gob.ec\/index.php\/prefectura-socializa-proyecto-de-politica-publica\/#primaryimage","url":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-03-at-14.16.44.jpeg","contentUrl":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-03-at-14.16.44.jpeg","width":1024,"height":827},{"@type":"BreadcrumbList","@id":"https:\/\/www.manabi.gob.ec\/index.php\/prefectura-socializa-proyecto-de-politica-publica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.manabi.gob.ec\/"},{"@type":"ListItem","position":2,"name":"PREFECTURA SOCIALIZA PROYECTO DE POL\u00cdTICA P\u00daBLICA"}]},{"@type":"WebSite","@id":"https:\/\/www.manabi.gob.ec\/#website","url":"https:\/\/www.manabi.gob.ec\/","name":"Prefectura de Manab\u00ed","description":"P\u00e1gina web de la prefectura","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.manabi.gob.ec\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.manabi.gob.ec\/#\/schema\/person\/c4f117989332ad723a6ced5994aa7d7a","name":"Lui Ochoa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g","caption":"Lui Ochoa"},"url":"https:\/\/www.manabi.gob.ec\/index.php\/author\/lochoa\/"}]}},"jetpack_featured_media_url":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-03-at-14.16.44.jpeg","_links":{"self":[{"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/posts\/25047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/comments?post=25047"}],"version-history":[{"count":0,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/posts\/25047\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/media\/25048"}],"wp:attachment":[{"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/media?parent=25047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/categories?post=25047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/tags?post=25047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}