{"id":25076,"date":"2023-07-07T17:31:51","date_gmt":"2023-07-07T17:31:51","guid":{"rendered":"https:\/\/www.manabi.gob.ec\/?p=25076"},"modified":"2023-07-07T17:31:56","modified_gmt":"2023-07-07T17:31:56","slug":"3-de-julio-se-cierra-al-transito-vehicular-en-el-puente-velasco-ibarra-ubicado-en-el-canton-pichincha","status":"publish","type":"post","link":"https:\/\/www.manabi.gob.ec\/index.php\/3-de-julio-se-cierra-al-transito-vehicular-en-el-puente-velasco-ibarra-ubicado-en-el-canton-pichincha\/","title":{"rendered":"3 de julio se cierra al tr\u00e1nsito vehicular en el puente Velasco Ibarra ubicado en el cant\u00f3n Pichincha."},"content":{"rendered":"\n<p>Desde las 00:00 horas de este lunes 3 julio el paso vehicular sobre el puente Velasco Ibarra en el cant\u00f3n Pichincha estar\u00e1 cerrado al tr\u00e1nsito; el paso peatonal se mantendr\u00e1 abierto.<\/p>\n\n\n\n<p>La repotenciaci\u00f3n del puente es una obra que se ejecuta con un aporte econ\u00f3mico de la instituci\u00f3n, sustentado mediante convenio tripartito entre la Prefectura de Manab\u00ed, Ministerio de Transporte y Obras P\u00fablicas, y el GAD Pichincha.<\/p>\n\n\n\n<p>En el contrato de repotenciaci\u00f3n del puente, se contempl\u00f3 la ejecuci\u00f3n de dos estructuras laterales que servir\u00e1n como paso peatonal definitivo, con el objeto de brindar seguridad a los ciudadanos que utilizan el puente.<\/p>\n\n\n\n<p>Los trabajos de repotenciaci\u00f3n del puente en su s\u00faperestructura tendr\u00e1n una duraci\u00f3n de 90 d\u00edas aproximadamente para la rehabilitaci\u00f3n del mismo.<\/p>\n\n\n\n<p>PLAN DE CONTINGENCIA VIAL<br>Mientras en el puente se realizan los trabajos, los veh\u00edculos podr\u00e1n tomar la v\u00eda alterna: Las Damas &#8211; Puerto Conguillo, que estar\u00e1 en constante mantenimiento por parte de la Prefectura.<\/p>\n\n\n\n<p>Es importante indicar que la Prefectura contrat\u00f3 la actualizaci\u00f3n de estudios para repotenciar el puente, y adem\u00e1s financia el 100% del costo de la fiscalizaci\u00f3n de los trabajos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde las 00:00 horas de este lunes 3 julio el paso vehicular sobre el puente Velasco Ibarra en el cant\u00f3n Pichincha estar\u00e1 cerrado al tr\u00e1nsito; el paso peatonal se mantendr\u00e1 abierto. La repotenciaci\u00f3n del puente es una obra que se ejecuta con un aporte econ\u00f3mico de la instituci\u00f3n, sustentado mediante convenio tripartito entre la Prefectura [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":25077,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[142,170,92,181,200,91,127],"tags":[],"class_list":["post-25076","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-desarrollo-social","category-manabi-vial","category-noticias-manabi","category-obra-publica","category-pichincha","category-todas","category-vialidad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>3 de julio se cierra al tr\u00e1nsito vehicular en el puente Velasco Ibarra ubicado en el cant\u00f3n Pichincha. - Prefectura de Manab\u00ed<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.manabi.gob.ec\/index.php\/3-de-julio-se-cierra-al-transito-vehicular-en-el-puente-velasco-ibarra-ubicado-en-el-canton-pichincha\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3 de julio se cierra al tr\u00e1nsito vehicular en el puente Velasco Ibarra ubicado en el cant\u00f3n Pichincha. - Prefectura de Manab\u00ed\" \/>\n<meta property=\"og:description\" content=\"Desde las 00:00 horas de este lunes 3 julio el paso vehicular sobre el puente Velasco Ibarra en el cant\u00f3n Pichincha estar\u00e1 cerrado al tr\u00e1nsito; el paso peatonal se mantendr\u00e1 abierto. La repotenciaci\u00f3n del puente es una obra que se ejecuta con un aporte econ\u00f3mico de la instituci\u00f3n, sustentado mediante convenio tripartito entre la Prefectura [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.manabi.gob.ec\/index.php\/3-de-julio-se-cierra-al-transito-vehicular-en-el-puente-velasco-ibarra-ubicado-en-el-canton-pichincha\/\" \/>\n<meta property=\"og:site_name\" content=\"Prefectura de Manab\u00ed\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-07T17:31:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-07T17:31:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-02-at-12.56.47.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"684\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lui Ochoa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lui Ochoa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/3-de-julio-se-cierra-al-transito-vehicular-en-el-puente-velasco-ibarra-ubicado-en-el-canton-pichincha\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/3-de-julio-se-cierra-al-transito-vehicular-en-el-puente-velasco-ibarra-ubicado-en-el-canton-pichincha\\\/\"},\"author\":{\"name\":\"Lui Ochoa\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/#\\\/schema\\\/person\\\/c4f117989332ad723a6ced5994aa7d7a\"},\"headline\":\"3 de julio se cierra al tr\u00e1nsito vehicular en el puente Velasco Ibarra ubicado en el cant\u00f3n Pichincha.\",\"datePublished\":\"2023-07-07T17:31:51+00:00\",\"dateModified\":\"2023-07-07T17:31:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/3-de-julio-se-cierra-al-transito-vehicular-en-el-puente-velasco-ibarra-ubicado-en-el-canton-pichincha\\\/\"},\"wordCount\":219,\"image\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/3-de-julio-se-cierra-al-transito-vehicular-en-el-puente-velasco-ibarra-ubicado-en-el-canton-pichincha\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.manabi.gob.ec\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/WhatsApp-Image-2023-07-02-at-12.56.47.jpeg\",\"articleSection\":[\"Desarrollo Social\",\"Manab\u00ed Vial\",\"Noticias\",\"Obra P\u00fablica\",\"Pichincha\",\"Todas\",\"Vialidad\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/3-de-julio-se-cierra-al-transito-vehicular-en-el-puente-velasco-ibarra-ubicado-en-el-canton-pichincha\\\/\",\"url\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/3-de-julio-se-cierra-al-transito-vehicular-en-el-puente-velasco-ibarra-ubicado-en-el-canton-pichincha\\\/\",\"name\":\"3 de julio se cierra al tr\u00e1nsito vehicular en el puente Velasco Ibarra ubicado en el cant\u00f3n Pichincha. - Prefectura de Manab\u00ed\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/3-de-julio-se-cierra-al-transito-vehicular-en-el-puente-velasco-ibarra-ubicado-en-el-canton-pichincha\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/3-de-julio-se-cierra-al-transito-vehicular-en-el-puente-velasco-ibarra-ubicado-en-el-canton-pichincha\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.manabi.gob.ec\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/WhatsApp-Image-2023-07-02-at-12.56.47.jpeg\",\"datePublished\":\"2023-07-07T17:31:51+00:00\",\"dateModified\":\"2023-07-07T17:31:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/#\\\/schema\\\/person\\\/c4f117989332ad723a6ced5994aa7d7a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/3-de-julio-se-cierra-al-transito-vehicular-en-el-puente-velasco-ibarra-ubicado-en-el-canton-pichincha\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/3-de-julio-se-cierra-al-transito-vehicular-en-el-puente-velasco-ibarra-ubicado-en-el-canton-pichincha\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/3-de-julio-se-cierra-al-transito-vehicular-en-el-puente-velasco-ibarra-ubicado-en-el-canton-pichincha\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.manabi.gob.ec\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/WhatsApp-Image-2023-07-02-at-12.56.47.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.manabi.gob.ec\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/WhatsApp-Image-2023-07-02-at-12.56.47.jpeg\",\"width\":1024,\"height\":684},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/3-de-julio-se-cierra-al-transito-vehicular-en-el-puente-velasco-ibarra-ubicado-en-el-canton-pichincha\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.manabi.gob.ec\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"3 de julio se cierra al tr\u00e1nsito vehicular en el puente Velasco Ibarra ubicado en el cant\u00f3n Pichincha.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/#website\",\"url\":\"https:\\\/\\\/www.manabi.gob.ec\\\/\",\"name\":\"Prefectura de Manab\u00ed\",\"description\":\"P\u00e1gina web de la prefectura\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.manabi.gob.ec\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/#\\\/schema\\\/person\\\/c4f117989332ad723a6ced5994aa7d7a\",\"name\":\"Lui Ochoa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g\",\"caption\":\"Lui Ochoa\"},\"url\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/author\\\/lochoa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"3 de julio se cierra al tr\u00e1nsito vehicular en el puente Velasco Ibarra ubicado en el cant\u00f3n Pichincha. - Prefectura de Manab\u00ed","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.manabi.gob.ec\/index.php\/3-de-julio-se-cierra-al-transito-vehicular-en-el-puente-velasco-ibarra-ubicado-en-el-canton-pichincha\/","og_locale":"es_ES","og_type":"article","og_title":"3 de julio se cierra al tr\u00e1nsito vehicular en el puente Velasco Ibarra ubicado en el cant\u00f3n Pichincha. - Prefectura de Manab\u00ed","og_description":"Desde las 00:00 horas de este lunes 3 julio el paso vehicular sobre el puente Velasco Ibarra en el cant\u00f3n Pichincha estar\u00e1 cerrado al tr\u00e1nsito; el paso peatonal se mantendr\u00e1 abierto. La repotenciaci\u00f3n del puente es una obra que se ejecuta con un aporte econ\u00f3mico de la instituci\u00f3n, sustentado mediante convenio tripartito entre la Prefectura [&hellip;]","og_url":"https:\/\/www.manabi.gob.ec\/index.php\/3-de-julio-se-cierra-al-transito-vehicular-en-el-puente-velasco-ibarra-ubicado-en-el-canton-pichincha\/","og_site_name":"Prefectura de Manab\u00ed","article_published_time":"2023-07-07T17:31:51+00:00","article_modified_time":"2023-07-07T17:31:56+00:00","og_image":[{"width":1024,"height":684,"url":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-02-at-12.56.47.jpeg","type":"image\/jpeg"}],"author":"Lui Ochoa","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Lui Ochoa","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.manabi.gob.ec\/index.php\/3-de-julio-se-cierra-al-transito-vehicular-en-el-puente-velasco-ibarra-ubicado-en-el-canton-pichincha\/#article","isPartOf":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/3-de-julio-se-cierra-al-transito-vehicular-en-el-puente-velasco-ibarra-ubicado-en-el-canton-pichincha\/"},"author":{"name":"Lui Ochoa","@id":"https:\/\/www.manabi.gob.ec\/#\/schema\/person\/c4f117989332ad723a6ced5994aa7d7a"},"headline":"3 de julio se cierra al tr\u00e1nsito vehicular en el puente Velasco Ibarra ubicado en el cant\u00f3n Pichincha.","datePublished":"2023-07-07T17:31:51+00:00","dateModified":"2023-07-07T17:31:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/3-de-julio-se-cierra-al-transito-vehicular-en-el-puente-velasco-ibarra-ubicado-en-el-canton-pichincha\/"},"wordCount":219,"image":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/3-de-julio-se-cierra-al-transito-vehicular-en-el-puente-velasco-ibarra-ubicado-en-el-canton-pichincha\/#primaryimage"},"thumbnailUrl":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-02-at-12.56.47.jpeg","articleSection":["Desarrollo Social","Manab\u00ed Vial","Noticias","Obra P\u00fablica","Pichincha","Todas","Vialidad"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.manabi.gob.ec\/index.php\/3-de-julio-se-cierra-al-transito-vehicular-en-el-puente-velasco-ibarra-ubicado-en-el-canton-pichincha\/","url":"https:\/\/www.manabi.gob.ec\/index.php\/3-de-julio-se-cierra-al-transito-vehicular-en-el-puente-velasco-ibarra-ubicado-en-el-canton-pichincha\/","name":"3 de julio se cierra al tr\u00e1nsito vehicular en el puente Velasco Ibarra ubicado en el cant\u00f3n Pichincha. - Prefectura de Manab\u00ed","isPartOf":{"@id":"https:\/\/www.manabi.gob.ec\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/3-de-julio-se-cierra-al-transito-vehicular-en-el-puente-velasco-ibarra-ubicado-en-el-canton-pichincha\/#primaryimage"},"image":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/3-de-julio-se-cierra-al-transito-vehicular-en-el-puente-velasco-ibarra-ubicado-en-el-canton-pichincha\/#primaryimage"},"thumbnailUrl":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-02-at-12.56.47.jpeg","datePublished":"2023-07-07T17:31:51+00:00","dateModified":"2023-07-07T17:31:56+00:00","author":{"@id":"https:\/\/www.manabi.gob.ec\/#\/schema\/person\/c4f117989332ad723a6ced5994aa7d7a"},"breadcrumb":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/3-de-julio-se-cierra-al-transito-vehicular-en-el-puente-velasco-ibarra-ubicado-en-el-canton-pichincha\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.manabi.gob.ec\/index.php\/3-de-julio-se-cierra-al-transito-vehicular-en-el-puente-velasco-ibarra-ubicado-en-el-canton-pichincha\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.manabi.gob.ec\/index.php\/3-de-julio-se-cierra-al-transito-vehicular-en-el-puente-velasco-ibarra-ubicado-en-el-canton-pichincha\/#primaryimage","url":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-02-at-12.56.47.jpeg","contentUrl":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-02-at-12.56.47.jpeg","width":1024,"height":684},{"@type":"BreadcrumbList","@id":"https:\/\/www.manabi.gob.ec\/index.php\/3-de-julio-se-cierra-al-transito-vehicular-en-el-puente-velasco-ibarra-ubicado-en-el-canton-pichincha\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.manabi.gob.ec\/"},{"@type":"ListItem","position":2,"name":"3 de julio se cierra al tr\u00e1nsito vehicular en el puente Velasco Ibarra ubicado en el cant\u00f3n Pichincha."}]},{"@type":"WebSite","@id":"https:\/\/www.manabi.gob.ec\/#website","url":"https:\/\/www.manabi.gob.ec\/","name":"Prefectura de Manab\u00ed","description":"P\u00e1gina web de la prefectura","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.manabi.gob.ec\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.manabi.gob.ec\/#\/schema\/person\/c4f117989332ad723a6ced5994aa7d7a","name":"Lui Ochoa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g","caption":"Lui Ochoa"},"url":"https:\/\/www.manabi.gob.ec\/index.php\/author\/lochoa\/"}]}},"jetpack_featured_media_url":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2023\/07\/WhatsApp-Image-2023-07-02-at-12.56.47.jpeg","_links":{"self":[{"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/posts\/25076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/comments?post=25076"}],"version-history":[{"count":0,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/posts\/25076\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/media\/25077"}],"wp:attachment":[{"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/media?parent=25076"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/categories?post=25076"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/tags?post=25076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}