{"id":26948,"date":"2024-01-19T23:53:01","date_gmt":"2024-01-19T23:53:01","guid":{"rendered":"https:\/\/www.manabi.gob.ec\/?p=26948"},"modified":"2024-01-19T23:53:07","modified_gmt":"2024-01-19T23:53:07","slug":"una-alianza-importante","status":"publish","type":"post","link":"https:\/\/www.manabi.gob.ec\/index.php\/una-alianza-importante\/","title":{"rendered":"\u00a1UNA ALIANZA IMPORTANTE !"},"content":{"rendered":"\n<p>Prefectura y MIES articulan acciones por el bienestar de los m\u00e1s vulnerables<\/p>\n\n\n\n<p>\u00abNecesitamos m\u00e1s gente comprometida y con esa calidad humana como usted\u00bb, expres\u00f3 la doctora Lizeth Piedra, delegada de la ministra del Ministerio de Inclusi\u00f3n Econ\u00f3mica y Social, Zaida Rovira, al prefecto Leonardo Orlando.<\/p>\n\n\n\n<p>Estas expresiones las realiz\u00f3 en el marco de la reuni\u00f3n que se efectu\u00f3 este jueves 18 de enero entre la autoridad provincial, la abogada Mar\u00eda Jos\u00e9 Fern\u00e1ndez Bravo, coordinadora zonal &#8211; 4 Manab\u00ed y Santo Domingo de los Ts\u00e1chilas, y el equipo t\u00e9cnico del MIES.<\/p>\n\n\n\n<p>El Prefecto conoci\u00f3 el cat\u00e1logo de servicios que ofrece el Ministerio de Inclusi\u00f3n Econ\u00f3mica y Social, en las \u00e1reas de desarrollo infantil, adulto mayor y personas con discapacidad.<\/p>\n\n\n\n<p>\u00abNosotros estamos convenidos de que esta es la mejor forma de contribuir a que nuestros ni\u00f1os y ni\u00f1as tengan una infancia plena\u00bb, sostuvo el Prefecto.<\/p>\n\n\n\n<p>\u00abVamos a firmar un convenio en los pr\u00f3ximos d\u00edas con la Prefectura, para lograr sostenibilidad y permanencia en los proyectos, y brindan una atenci\u00f3n integral a los grupos de atenci\u00f3n prioritaria en Manab\u00ed\u00bb, dijo la coordinadora zonal del MIES.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prefectura y MIES articulan acciones por el bienestar de los m\u00e1s vulnerables \u00abNecesitamos m\u00e1s gente comprometida y con esa calidad humana como usted\u00bb, expres\u00f3 la doctora Lizeth Piedra, delegada de la ministra del Ministerio de Inclusi\u00f3n Econ\u00f3mica y Social, Zaida Rovira, al prefecto Leonardo Orlando. Estas expresiones las realiz\u00f3 en el marco de la reuni\u00f3n [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":26949,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[150,142,92,91,223],"tags":[],"class_list":["post-26948","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ambiente","category-desarrollo-social","category-noticias-manabi","category-todas","category-violencia-de-genero"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00a1UNA ALIANZA IMPORTANTE ! - Prefectura de Manab\u00ed<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.manabi.gob.ec\/index.php\/una-alianza-importante\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a1UNA ALIANZA IMPORTANTE ! - Prefectura de Manab\u00ed\" \/>\n<meta property=\"og:description\" content=\"Prefectura y MIES articulan acciones por el bienestar de los m\u00e1s vulnerables \u00abNecesitamos m\u00e1s gente comprometida y con esa calidad humana como usted\u00bb, expres\u00f3 la doctora Lizeth Piedra, delegada de la ministra del Ministerio de Inclusi\u00f3n Econ\u00f3mica y Social, Zaida Rovira, al prefecto Leonardo Orlando. Estas expresiones las realiz\u00f3 en el marco de la reuni\u00f3n [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.manabi.gob.ec\/index.php\/una-alianza-importante\/\" \/>\n<meta property=\"og:site_name\" content=\"Prefectura de Manab\u00ed\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-19T23:53:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-19T23:53:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-18-at-16.28.20.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lui Ochoa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lui Ochoa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/una-alianza-importante\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/una-alianza-importante\\\/\"},\"author\":{\"name\":\"Lui Ochoa\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/#\\\/schema\\\/person\\\/c4f117989332ad723a6ced5994aa7d7a\"},\"headline\":\"\u00a1UNA ALIANZA IMPORTANTE !\",\"datePublished\":\"2024-01-19T23:53:01+00:00\",\"dateModified\":\"2024-01-19T23:53:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/una-alianza-importante\\\/\"},\"wordCount\":201,\"image\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/una-alianza-importante\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.manabi.gob.ec\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/WhatsApp-Image-2024-01-18-at-16.28.20.jpeg\",\"articleSection\":[\"Ambiente\",\"Desarrollo Social\",\"Noticias\",\"Todas\",\"Violencia de G\u00e9nero\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/una-alianza-importante\\\/\",\"url\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/una-alianza-importante\\\/\",\"name\":\"\u00a1UNA ALIANZA IMPORTANTE ! - Prefectura de Manab\u00ed\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/una-alianza-importante\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/una-alianza-importante\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.manabi.gob.ec\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/WhatsApp-Image-2024-01-18-at-16.28.20.jpeg\",\"datePublished\":\"2024-01-19T23:53:01+00:00\",\"dateModified\":\"2024-01-19T23:53:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/#\\\/schema\\\/person\\\/c4f117989332ad723a6ced5994aa7d7a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/una-alianza-importante\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/una-alianza-importante\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/una-alianza-importante\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.manabi.gob.ec\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/WhatsApp-Image-2024-01-18-at-16.28.20.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.manabi.gob.ec\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/WhatsApp-Image-2024-01-18-at-16.28.20.jpeg\",\"width\":1024,\"height\":682},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/una-alianza-importante\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.manabi.gob.ec\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00a1UNA ALIANZA IMPORTANTE !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/#website\",\"url\":\"https:\\\/\\\/www.manabi.gob.ec\\\/\",\"name\":\"Prefectura de Manab\u00ed\",\"description\":\"P\u00e1gina web de la prefectura\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.manabi.gob.ec\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/#\\\/schema\\\/person\\\/c4f117989332ad723a6ced5994aa7d7a\",\"name\":\"Lui Ochoa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g\",\"caption\":\"Lui Ochoa\"},\"url\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/author\\\/lochoa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a1UNA ALIANZA IMPORTANTE ! - Prefectura de Manab\u00ed","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.manabi.gob.ec\/index.php\/una-alianza-importante\/","og_locale":"es_ES","og_type":"article","og_title":"\u00a1UNA ALIANZA IMPORTANTE ! - Prefectura de Manab\u00ed","og_description":"Prefectura y MIES articulan acciones por el bienestar de los m\u00e1s vulnerables \u00abNecesitamos m\u00e1s gente comprometida y con esa calidad humana como usted\u00bb, expres\u00f3 la doctora Lizeth Piedra, delegada de la ministra del Ministerio de Inclusi\u00f3n Econ\u00f3mica y Social, Zaida Rovira, al prefecto Leonardo Orlando. Estas expresiones las realiz\u00f3 en el marco de la reuni\u00f3n [&hellip;]","og_url":"https:\/\/www.manabi.gob.ec\/index.php\/una-alianza-importante\/","og_site_name":"Prefectura de Manab\u00ed","article_published_time":"2024-01-19T23:53:01+00:00","article_modified_time":"2024-01-19T23:53:07+00:00","og_image":[{"width":1024,"height":682,"url":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-18-at-16.28.20.jpeg","type":"image\/jpeg"}],"author":"Lui Ochoa","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Lui Ochoa","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.manabi.gob.ec\/index.php\/una-alianza-importante\/#article","isPartOf":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/una-alianza-importante\/"},"author":{"name":"Lui Ochoa","@id":"https:\/\/www.manabi.gob.ec\/#\/schema\/person\/c4f117989332ad723a6ced5994aa7d7a"},"headline":"\u00a1UNA ALIANZA IMPORTANTE !","datePublished":"2024-01-19T23:53:01+00:00","dateModified":"2024-01-19T23:53:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/una-alianza-importante\/"},"wordCount":201,"image":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/una-alianza-importante\/#primaryimage"},"thumbnailUrl":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-18-at-16.28.20.jpeg","articleSection":["Ambiente","Desarrollo Social","Noticias","Todas","Violencia de G\u00e9nero"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.manabi.gob.ec\/index.php\/una-alianza-importante\/","url":"https:\/\/www.manabi.gob.ec\/index.php\/una-alianza-importante\/","name":"\u00a1UNA ALIANZA IMPORTANTE ! - Prefectura de Manab\u00ed","isPartOf":{"@id":"https:\/\/www.manabi.gob.ec\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/una-alianza-importante\/#primaryimage"},"image":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/una-alianza-importante\/#primaryimage"},"thumbnailUrl":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-18-at-16.28.20.jpeg","datePublished":"2024-01-19T23:53:01+00:00","dateModified":"2024-01-19T23:53:07+00:00","author":{"@id":"https:\/\/www.manabi.gob.ec\/#\/schema\/person\/c4f117989332ad723a6ced5994aa7d7a"},"breadcrumb":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/una-alianza-importante\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.manabi.gob.ec\/index.php\/una-alianza-importante\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.manabi.gob.ec\/index.php\/una-alianza-importante\/#primaryimage","url":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-18-at-16.28.20.jpeg","contentUrl":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-18-at-16.28.20.jpeg","width":1024,"height":682},{"@type":"BreadcrumbList","@id":"https:\/\/www.manabi.gob.ec\/index.php\/una-alianza-importante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.manabi.gob.ec\/"},{"@type":"ListItem","position":2,"name":"\u00a1UNA ALIANZA IMPORTANTE !"}]},{"@type":"WebSite","@id":"https:\/\/www.manabi.gob.ec\/#website","url":"https:\/\/www.manabi.gob.ec\/","name":"Prefectura de Manab\u00ed","description":"P\u00e1gina web de la prefectura","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.manabi.gob.ec\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.manabi.gob.ec\/#\/schema\/person\/c4f117989332ad723a6ced5994aa7d7a","name":"Lui Ochoa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g","caption":"Lui Ochoa"},"url":"https:\/\/www.manabi.gob.ec\/index.php\/author\/lochoa\/"}]}},"jetpack_featured_media_url":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-18-at-16.28.20.jpeg","_links":{"self":[{"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/posts\/26948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/comments?post=26948"}],"version-history":[{"count":1,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/posts\/26948\/revisions"}],"predecessor-version":[{"id":26950,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/posts\/26948\/revisions\/26950"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/media\/26949"}],"wp:attachment":[{"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/media?parent=26948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/categories?post=26948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/tags?post=26948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}