{"id":26951,"date":"2024-01-19T23:56:22","date_gmt":"2024-01-19T23:56:22","guid":{"rendered":"https:\/\/www.manabi.gob.ec\/?p=26951"},"modified":"2024-01-19T23:56:27","modified_gmt":"2024-01-19T23:56:27","slug":"manabi-lo-logro","status":"publish","type":"post","link":"https:\/\/www.manabi.gob.ec\/index.php\/manabi-lo-logro\/","title":{"rendered":"\u00a1Manab\u00ed lo logr\u00f3!"},"content":{"rendered":"\n<p>Se aprob\u00f3 cr\u00e9dito con organismo internacional para construir el proyecto vial m\u00e1s grande de la provincia hasta la fecha.<\/p>\n\n\n\n<p>La ma\u00f1ana de este 18 de enero, el prefecto de Manab\u00ed, Leonardo Orlando recibi\u00f3 la notificaci\u00f3n por parte del Banco de Desarrollo para Am\u00e9rica Latina y el Caribe (CAF), de la aprobaci\u00f3n del cr\u00e9dito de m\u00e1s de 43 millones de d\u00f3lares para tres proyectos viales que unen al norte, centro y sur de la provincia.<\/p>\n\n\n\n<p>Los tres proyectos viales son:<br>\u2022 Rehabilitaci\u00f3n, mejoramiento y ampliaci\u00f3n de 38.7km de la v\u00eda Quiroga \u2013 El Desv\u00edo, que une los cantones Bol\u00edvar y Pichincha; y tramo de la v\u00eda Calceta-Quiroga, adem\u00e1s del acceso al nuevo campus que tendr\u00e1 la ULEAM en el cant\u00f3n Pichincha, incrementando el proyecto vial a 51 km.<br>\u2022 Construcci\u00f3n de 31km de la v\u00eda Ayacucho (desde el km 10) \u2013 La Uni\u00f3n \u2013 San Pablo de Pueblo Nuevo del cant\u00f3n Santa Ana; y Tramo San Juan de las Cucarachas \u2013 Agua Fr\u00eda, con el l\u00edmite provincial, incrementando a 41 km.<br>\u2022 Construcci\u00f3n de 22.2 km de la v\u00eda Col\u00f3n \u2013 Quimis, que integra los cantones Portoviejo y Jipijapa.<\/p>\n\n\n\n<p>\u201cM\u00e1s de 118 km quedar\u00e1n como v\u00edas de primer orden, con todos los componentes para la transformaci\u00f3n y desarrollo de nuestra provincia. Este logro hist\u00f3rico se da por primera vez para la Prefectura y es el cr\u00e9dito para vialidad m\u00e1s grande y por primera vez un organismo multilateral como CAF de manera directa, financia a la Prefectura\u201d, expres\u00f3 el prefecto en el anuncio de esta noticia a los manabitas.<\/p>\n\n\n\n<p>La Prefectura ahora continuar\u00e1 con las siguientes gestiones ante el pleno del Consejo Provincial y con el Gobierno central para la obtenci\u00f3n de la garant\u00eda soberana y seguir con el proceso de este proyecto hist\u00f3rico que impulsar\u00e1 el desarrollo de Manab\u00ed.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se aprob\u00f3 cr\u00e9dito con organismo internacional para construir el proyecto vial m\u00e1s grande de la provincia hasta la fecha. La ma\u00f1ana de este 18 de enero, el prefecto de Manab\u00ed, Leonardo Orlando recibi\u00f3 la notificaci\u00f3n por parte del Banco de Desarrollo para Am\u00e9rica Latina y el Caribe (CAF), de la aprobaci\u00f3n del cr\u00e9dito de m\u00e1s [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":26952,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[150,142,92,181,91],"tags":[],"class_list":["post-26951","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ambiente","category-desarrollo-social","category-noticias-manabi","category-obra-publica","category-todas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00a1Manab\u00ed lo logr\u00f3! - Prefectura de Manab\u00ed<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.manabi.gob.ec\/index.php\/manabi-lo-logro\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a1Manab\u00ed lo logr\u00f3! - Prefectura de Manab\u00ed\" \/>\n<meta property=\"og:description\" content=\"Se aprob\u00f3 cr\u00e9dito con organismo internacional para construir el proyecto vial m\u00e1s grande de la provincia hasta la fecha. La ma\u00f1ana de este 18 de enero, el prefecto de Manab\u00ed, Leonardo Orlando recibi\u00f3 la notificaci\u00f3n por parte del Banco de Desarrollo para Am\u00e9rica Latina y el Caribe (CAF), de la aprobaci\u00f3n del cr\u00e9dito de m\u00e1s [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.manabi.gob.ec\/index.php\/manabi-lo-logro\/\" \/>\n<meta property=\"og:site_name\" content=\"Prefectura de Manab\u00ed\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-19T23:56:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-19T23:56:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-18-at-20.04.06.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lui Ochoa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lui Ochoa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/manabi-lo-logro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/manabi-lo-logro\\\/\"},\"author\":{\"name\":\"Lui Ochoa\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/#\\\/schema\\\/person\\\/c4f117989332ad723a6ced5994aa7d7a\"},\"headline\":\"\u00a1Manab\u00ed lo logr\u00f3!\",\"datePublished\":\"2024-01-19T23:56:22+00:00\",\"dateModified\":\"2024-01-19T23:56:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/manabi-lo-logro\\\/\"},\"wordCount\":322,\"image\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/manabi-lo-logro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.manabi.gob.ec\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/WhatsApp-Image-2024-01-18-at-20.04.06.jpeg\",\"articleSection\":[\"Ambiente\",\"Desarrollo Social\",\"Noticias\",\"Obra P\u00fablica\",\"Todas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/manabi-lo-logro\\\/\",\"url\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/manabi-lo-logro\\\/\",\"name\":\"\u00a1Manab\u00ed lo logr\u00f3! - Prefectura de Manab\u00ed\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/manabi-lo-logro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/manabi-lo-logro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.manabi.gob.ec\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/WhatsApp-Image-2024-01-18-at-20.04.06.jpeg\",\"datePublished\":\"2024-01-19T23:56:22+00:00\",\"dateModified\":\"2024-01-19T23:56:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/#\\\/schema\\\/person\\\/c4f117989332ad723a6ced5994aa7d7a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/manabi-lo-logro\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/manabi-lo-logro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/manabi-lo-logro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.manabi.gob.ec\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/WhatsApp-Image-2024-01-18-at-20.04.06.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.manabi.gob.ec\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/WhatsApp-Image-2024-01-18-at-20.04.06.jpeg\",\"width\":1024,\"height\":682},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/manabi-lo-logro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.manabi.gob.ec\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00a1Manab\u00ed lo logr\u00f3!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/#website\",\"url\":\"https:\\\/\\\/www.manabi.gob.ec\\\/\",\"name\":\"Prefectura de Manab\u00ed\",\"description\":\"P\u00e1gina web de la prefectura\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.manabi.gob.ec\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/#\\\/schema\\\/person\\\/c4f117989332ad723a6ced5994aa7d7a\",\"name\":\"Lui Ochoa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g\",\"caption\":\"Lui Ochoa\"},\"url\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/author\\\/lochoa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a1Manab\u00ed lo logr\u00f3! - Prefectura de Manab\u00ed","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.manabi.gob.ec\/index.php\/manabi-lo-logro\/","og_locale":"es_ES","og_type":"article","og_title":"\u00a1Manab\u00ed lo logr\u00f3! - Prefectura de Manab\u00ed","og_description":"Se aprob\u00f3 cr\u00e9dito con organismo internacional para construir el proyecto vial m\u00e1s grande de la provincia hasta la fecha. La ma\u00f1ana de este 18 de enero, el prefecto de Manab\u00ed, Leonardo Orlando recibi\u00f3 la notificaci\u00f3n por parte del Banco de Desarrollo para Am\u00e9rica Latina y el Caribe (CAF), de la aprobaci\u00f3n del cr\u00e9dito de m\u00e1s [&hellip;]","og_url":"https:\/\/www.manabi.gob.ec\/index.php\/manabi-lo-logro\/","og_site_name":"Prefectura de Manab\u00ed","article_published_time":"2024-01-19T23:56:22+00:00","article_modified_time":"2024-01-19T23:56:27+00:00","og_image":[{"width":1024,"height":682,"url":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-18-at-20.04.06.jpeg","type":"image\/jpeg"}],"author":"Lui Ochoa","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Lui Ochoa","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.manabi.gob.ec\/index.php\/manabi-lo-logro\/#article","isPartOf":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/manabi-lo-logro\/"},"author":{"name":"Lui Ochoa","@id":"https:\/\/www.manabi.gob.ec\/#\/schema\/person\/c4f117989332ad723a6ced5994aa7d7a"},"headline":"\u00a1Manab\u00ed lo logr\u00f3!","datePublished":"2024-01-19T23:56:22+00:00","dateModified":"2024-01-19T23:56:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/manabi-lo-logro\/"},"wordCount":322,"image":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/manabi-lo-logro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-18-at-20.04.06.jpeg","articleSection":["Ambiente","Desarrollo Social","Noticias","Obra P\u00fablica","Todas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.manabi.gob.ec\/index.php\/manabi-lo-logro\/","url":"https:\/\/www.manabi.gob.ec\/index.php\/manabi-lo-logro\/","name":"\u00a1Manab\u00ed lo logr\u00f3! - Prefectura de Manab\u00ed","isPartOf":{"@id":"https:\/\/www.manabi.gob.ec\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/manabi-lo-logro\/#primaryimage"},"image":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/manabi-lo-logro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-18-at-20.04.06.jpeg","datePublished":"2024-01-19T23:56:22+00:00","dateModified":"2024-01-19T23:56:27+00:00","author":{"@id":"https:\/\/www.manabi.gob.ec\/#\/schema\/person\/c4f117989332ad723a6ced5994aa7d7a"},"breadcrumb":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/manabi-lo-logro\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.manabi.gob.ec\/index.php\/manabi-lo-logro\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.manabi.gob.ec\/index.php\/manabi-lo-logro\/#primaryimage","url":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-18-at-20.04.06.jpeg","contentUrl":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-18-at-20.04.06.jpeg","width":1024,"height":682},{"@type":"BreadcrumbList","@id":"https:\/\/www.manabi.gob.ec\/index.php\/manabi-lo-logro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.manabi.gob.ec\/"},{"@type":"ListItem","position":2,"name":"\u00a1Manab\u00ed lo logr\u00f3!"}]},{"@type":"WebSite","@id":"https:\/\/www.manabi.gob.ec\/#website","url":"https:\/\/www.manabi.gob.ec\/","name":"Prefectura de Manab\u00ed","description":"P\u00e1gina web de la prefectura","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.manabi.gob.ec\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.manabi.gob.ec\/#\/schema\/person\/c4f117989332ad723a6ced5994aa7d7a","name":"Lui Ochoa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g","caption":"Lui Ochoa"},"url":"https:\/\/www.manabi.gob.ec\/index.php\/author\/lochoa\/"}]}},"jetpack_featured_media_url":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-18-at-20.04.06.jpeg","_links":{"self":[{"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/posts\/26951","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/comments?post=26951"}],"version-history":[{"count":1,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/posts\/26951\/revisions"}],"predecessor-version":[{"id":26953,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/posts\/26951\/revisions\/26953"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/media\/26952"}],"wp:attachment":[{"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/media?parent=26951"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/categories?post=26951"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/tags?post=26951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}