{"id":30361,"date":"2025-04-02T20:26:40","date_gmt":"2025-04-02T20:26:40","guid":{"rendered":"https:\/\/www.manabi.gob.ec\/?p=30361"},"modified":"2025-04-02T20:26:45","modified_gmt":"2025-04-02T20:26:45","slug":"super-combate-de-arqueros-este-sabado-en-portoviejo","status":"publish","type":"post","link":"https:\/\/www.manabi.gob.ec\/index.php\/super-combate-de-arqueros-este-sabado-en-portoviejo\/","title":{"rendered":"S\u00faper combate de arqueros este s\u00e1bado en Portoviejo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Portoviejo se apresta a vivir uno de los eventos deportivos m\u00e1s importantes del a\u00f1o, con el S\u00faper Combate de Arqueros Nacional, que se desarrollar\u00e1 el pr\u00f3ximo s\u00e1bado 5 de abril en las canchas sint\u00e9ticas La Rotonda,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El el evento lo organiza la Escuela de Arqueros M12 en la capital de la provincia, y cuenta con el auspicio de la Prefectura de Manab\u00ed, indic\u00f3 Silvio Larrea, responsable del \u00e1rea de deportes de la entidad provincial, destac\u00f3 la importancia del certamen quien dijo que contar\u00e1n con la participaci\u00f3n de figuras del deporte no solo de la provincia, sino del pa\u00eds y sino destacados arqueros conocidos a nivel internacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Varias escuelas a nivel nacional y arqueros extranjeros en diferentes categor\u00edas ser\u00e1n los protagonistas ya han confirmado su presencia a esta cita deportiva, donde mostrar\u00e1n toda su destreza en el arco, para poder lograr los primeros lugares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con la organizaci\u00f3n de este evento deportivo tambi\u00e9n se busca apoyar a la reactivaci\u00f3n econ\u00f3mica de la ciudad y provincia, manifest\u00f3 el funcionario de la Prefectura, en una rueda de prensa que ofreci\u00f3 la tarde de este 2 de abril.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El evento es gratuito, y se desarrollar\u00e1 durante todo el d\u00eda s\u00e1bado, una oportunidad para compartir una jornada en familia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Portoviejo se apresta a vivir uno de los eventos deportivos m\u00e1s importantes del a\u00f1o, con el S\u00faper Combate de Arqueros Nacional, que se desarrollar\u00e1 el pr\u00f3ximo s\u00e1bado 5 de abril en las canchas sint\u00e9ticas La Rotonda, El el evento lo organiza la Escuela de Arqueros M12 en la capital de la provincia, y cuenta con [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":30362,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[150,142,92,132,91],"tags":[],"class_list":["post-30361","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ambiente","category-desarrollo-social","category-noticias-manabi","category-portoviejo","category-todas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>S\u00faper combate de arqueros este s\u00e1bado en Portoviejo - Prefectura de Manab\u00ed<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.manabi.gob.ec\/index.php\/super-combate-de-arqueros-este-sabado-en-portoviejo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00faper combate de arqueros este s\u00e1bado en Portoviejo - Prefectura de Manab\u00ed\" \/>\n<meta property=\"og:description\" content=\"Portoviejo se apresta a vivir uno de los eventos deportivos m\u00e1s importantes del a\u00f1o, con el S\u00faper Combate de Arqueros Nacional, que se desarrollar\u00e1 el pr\u00f3ximo s\u00e1bado 5 de abril en las canchas sint\u00e9ticas La Rotonda, El el evento lo organiza la Escuela de Arqueros M12 en la capital de la provincia, y cuenta con [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.manabi.gob.ec\/index.php\/super-combate-de-arqueros-este-sabado-en-portoviejo\/\" \/>\n<meta property=\"og:site_name\" content=\"Prefectura de Manab\u00ed\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-02T20:26:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-02T20:26:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2025\/04\/7D0A9706-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1868\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lui Ochoa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lui Ochoa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/super-combate-de-arqueros-este-sabado-en-portoviejo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/super-combate-de-arqueros-este-sabado-en-portoviejo\\\/\"},\"author\":{\"name\":\"Lui Ochoa\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/#\\\/schema\\\/person\\\/c4f117989332ad723a6ced5994aa7d7a\"},\"headline\":\"S\u00faper combate de arqueros este s\u00e1bado en Portoviejo\",\"datePublished\":\"2025-04-02T20:26:40+00:00\",\"dateModified\":\"2025-04-02T20:26:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/super-combate-de-arqueros-este-sabado-en-portoviejo\\\/\"},\"wordCount\":229,\"image\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/super-combate-de-arqueros-este-sabado-en-portoviejo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.manabi.gob.ec\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/7D0A9706-scaled.jpg\",\"articleSection\":[\"Ambiente\",\"Desarrollo Social\",\"Noticias\",\"Portoviejo\",\"Todas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/super-combate-de-arqueros-este-sabado-en-portoviejo\\\/\",\"url\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/super-combate-de-arqueros-este-sabado-en-portoviejo\\\/\",\"name\":\"S\u00faper combate de arqueros este s\u00e1bado en Portoviejo - Prefectura de Manab\u00ed\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/super-combate-de-arqueros-este-sabado-en-portoviejo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/super-combate-de-arqueros-este-sabado-en-portoviejo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.manabi.gob.ec\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/7D0A9706-scaled.jpg\",\"datePublished\":\"2025-04-02T20:26:40+00:00\",\"dateModified\":\"2025-04-02T20:26:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/#\\\/schema\\\/person\\\/c4f117989332ad723a6ced5994aa7d7a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/super-combate-de-arqueros-este-sabado-en-portoviejo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/super-combate-de-arqueros-este-sabado-en-portoviejo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/super-combate-de-arqueros-este-sabado-en-portoviejo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.manabi.gob.ec\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/7D0A9706-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.manabi.gob.ec\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/7D0A9706-scaled.jpg\",\"width\":2560,\"height\":1868},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/super-combate-de-arqueros-este-sabado-en-portoviejo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.manabi.gob.ec\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"S\u00faper combate de arqueros este s\u00e1bado en Portoviejo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/#website\",\"url\":\"https:\\\/\\\/www.manabi.gob.ec\\\/\",\"name\":\"Prefectura de Manab\u00ed\",\"description\":\"P\u00e1gina web de la prefectura\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.manabi.gob.ec\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.manabi.gob.ec\\\/#\\\/schema\\\/person\\\/c4f117989332ad723a6ced5994aa7d7a\",\"name\":\"Lui Ochoa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g\",\"caption\":\"Lui Ochoa\"},\"url\":\"https:\\\/\\\/www.manabi.gob.ec\\\/index.php\\\/author\\\/lochoa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"S\u00faper combate de arqueros este s\u00e1bado en Portoviejo - Prefectura de Manab\u00ed","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.manabi.gob.ec\/index.php\/super-combate-de-arqueros-este-sabado-en-portoviejo\/","og_locale":"es_ES","og_type":"article","og_title":"S\u00faper combate de arqueros este s\u00e1bado en Portoviejo - Prefectura de Manab\u00ed","og_description":"Portoviejo se apresta a vivir uno de los eventos deportivos m\u00e1s importantes del a\u00f1o, con el S\u00faper Combate de Arqueros Nacional, que se desarrollar\u00e1 el pr\u00f3ximo s\u00e1bado 5 de abril en las canchas sint\u00e9ticas La Rotonda, El el evento lo organiza la Escuela de Arqueros M12 en la capital de la provincia, y cuenta con [&hellip;]","og_url":"https:\/\/www.manabi.gob.ec\/index.php\/super-combate-de-arqueros-este-sabado-en-portoviejo\/","og_site_name":"Prefectura de Manab\u00ed","article_published_time":"2025-04-02T20:26:40+00:00","article_modified_time":"2025-04-02T20:26:45+00:00","og_image":[{"width":2560,"height":1868,"url":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2025\/04\/7D0A9706-scaled.jpg","type":"image\/jpeg"}],"author":"Lui Ochoa","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Lui Ochoa","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.manabi.gob.ec\/index.php\/super-combate-de-arqueros-este-sabado-en-portoviejo\/#article","isPartOf":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/super-combate-de-arqueros-este-sabado-en-portoviejo\/"},"author":{"name":"Lui Ochoa","@id":"https:\/\/www.manabi.gob.ec\/#\/schema\/person\/c4f117989332ad723a6ced5994aa7d7a"},"headline":"S\u00faper combate de arqueros este s\u00e1bado en Portoviejo","datePublished":"2025-04-02T20:26:40+00:00","dateModified":"2025-04-02T20:26:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/super-combate-de-arqueros-este-sabado-en-portoviejo\/"},"wordCount":229,"image":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/super-combate-de-arqueros-este-sabado-en-portoviejo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2025\/04\/7D0A9706-scaled.jpg","articleSection":["Ambiente","Desarrollo Social","Noticias","Portoviejo","Todas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.manabi.gob.ec\/index.php\/super-combate-de-arqueros-este-sabado-en-portoviejo\/","url":"https:\/\/www.manabi.gob.ec\/index.php\/super-combate-de-arqueros-este-sabado-en-portoviejo\/","name":"S\u00faper combate de arqueros este s\u00e1bado en Portoviejo - Prefectura de Manab\u00ed","isPartOf":{"@id":"https:\/\/www.manabi.gob.ec\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/super-combate-de-arqueros-este-sabado-en-portoviejo\/#primaryimage"},"image":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/super-combate-de-arqueros-este-sabado-en-portoviejo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2025\/04\/7D0A9706-scaled.jpg","datePublished":"2025-04-02T20:26:40+00:00","dateModified":"2025-04-02T20:26:45+00:00","author":{"@id":"https:\/\/www.manabi.gob.ec\/#\/schema\/person\/c4f117989332ad723a6ced5994aa7d7a"},"breadcrumb":{"@id":"https:\/\/www.manabi.gob.ec\/index.php\/super-combate-de-arqueros-este-sabado-en-portoviejo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.manabi.gob.ec\/index.php\/super-combate-de-arqueros-este-sabado-en-portoviejo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.manabi.gob.ec\/index.php\/super-combate-de-arqueros-este-sabado-en-portoviejo\/#primaryimage","url":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2025\/04\/7D0A9706-scaled.jpg","contentUrl":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2025\/04\/7D0A9706-scaled.jpg","width":2560,"height":1868},{"@type":"BreadcrumbList","@id":"https:\/\/www.manabi.gob.ec\/index.php\/super-combate-de-arqueros-este-sabado-en-portoviejo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.manabi.gob.ec\/"},{"@type":"ListItem","position":2,"name":"S\u00faper combate de arqueros este s\u00e1bado en Portoviejo"}]},{"@type":"WebSite","@id":"https:\/\/www.manabi.gob.ec\/#website","url":"https:\/\/www.manabi.gob.ec\/","name":"Prefectura de Manab\u00ed","description":"P\u00e1gina web de la prefectura","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.manabi.gob.ec\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.manabi.gob.ec\/#\/schema\/person\/c4f117989332ad723a6ced5994aa7d7a","name":"Lui Ochoa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6e8017d0fe69dead8a95864d2eb6e1e1d8bf8e01194ba49cf7b897ff038126ba?s=96&d=mm&r=g","caption":"Lui Ochoa"},"url":"https:\/\/www.manabi.gob.ec\/index.php\/author\/lochoa\/"}]}},"jetpack_featured_media_url":"https:\/\/www.manabi.gob.ec\/wp-content\/uploads\/2025\/04\/7D0A9706-scaled.jpg","_links":{"self":[{"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/posts\/30361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/comments?post=30361"}],"version-history":[{"count":1,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/posts\/30361\/revisions"}],"predecessor-version":[{"id":30363,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/posts\/30361\/revisions\/30363"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/media\/30362"}],"wp:attachment":[{"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/media?parent=30361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/categories?post=30361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.manabi.gob.ec\/index.php\/wp-json\/wp\/v2\/tags?post=30361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}